{"id":7774,"date":"2025-12-11T21:00:53","date_gmt":"2025-12-11T20:00:53","guid":{"rendered":"https:\/\/www.chromacon.com\/ueber-chromacon\/"},"modified":"2026-05-12T15:15:18","modified_gmt":"2026-05-12T13:15:18","slug":"ueber-chromacon","status":"publish","type":"page","link":"https:\/\/www.chromacon.com\/de\/ueber-chromacon\/","title":{"rendered":"\u00dcber ChromaCon"},"content":{"rendered":"<section id=\"block_96fe9df365a4b93f86a7f2d7b008a398\" class=\"block-hero alignfull  \">\n    <div class=\"block-hero__background\">\n        <div class=\"block-hero__wrapper wrapper-bl-l\">\n            <div class=\"block-hero__content\">\n                <div class=\"block-hero__text\">\n                    <div class=\"block-hero__heading\">\n                                                    <p class=\"block-hero__eyebrow uppercase border border-primary-800\/30 text-primary-800 rounded-full px-4 py-2 text-16\">\n                                \u00dcBER UNS                            <\/p>\n                        \n                                                    <h1 class=\"text-display-m leading-display-m text-primary-800 [&#038;_strong]:text-secondary-700 [&#038;_strong]:font-medium typo-off\">\n                                Das Team hinter der <strong>kontinuierlichen Chromatographie<\/strong>\n                            <\/h1>\n                        \n                                                    <div class=\"block-hero__description\">\n                                <p>Erfinder von MCSGP, CaptureSMB\u00ae und N-Rich\u00ae \u2013 jener Doppel-S\u00e4ulen-Prozesse, die nun im kommerziellen GMP-Ma\u00dfstab bei Bachem und Bristol Myers Squibb validiert sind. Ans\u00e4ssig in Z\u00fcrich, weltweit pr\u00e4sent \u00fcber YMC. <\/p>\n                            <\/div>\n                                            <\/div>\n\n                                            <div class=\"block-hero__buttons flex flex-row flex-wrap items-start gap-[30px]\">\n                                                            <div class=\"block-hero__button\">\n                                    <span class=\"c-btn-focus-wrapper\"><a href=\"#contact-form\" class=\"c-btn c-btn--regular c-btn--primary c-btn--light\"><span>Sprechen Sie mit einem Experten<\/span><\/a><\/span>                                <\/div>\n                                                                                        <div class=\"block-hero__button block-hero__button--secondary\">\n                                    <span class=\"c-btn-focus-wrapper\"><a href=\"https:\/\/www.chromacon.com\/de\/dienstleistungen\/demos-einfuehrungen\/\" class=\"c-btn c-btn--regular c-btn--secondary c-btn--light\"><span>Besuchen Sie unser Applikationslabor<\/span><\/a><\/span>                                <\/div>\n                                                    <\/div>\n                                    <\/div>\n            <\/div>\n\n            <div class=\"block-hero__image-section\">\n                <div class=\"block-hero__image-container typo-off\">\n                                            <div class=\"block-hero__image\">\n                            <img fetchpriority=\"high\" decoding=\"async\" width=\"2240\" height=\"1888\" src=\"https:\/\/www.chromacon.com\/wp-content\/uploads\/2025\/12\/Gemini_Generated_Image_vq3a03vq3a03vq3a.jpg\" class=\"block-hero__image-img\" alt=\"\" loading=\"eager\" srcset=\"https:\/\/www.chromacon.com\/wp-content\/uploads\/2025\/12\/Gemini_Generated_Image_vq3a03vq3a03vq3a.jpg 2240w, https:\/\/www.chromacon.com\/wp-content\/uploads\/2025\/12\/Gemini_Generated_Image_vq3a03vq3a03vq3a-300x253.jpg 300w, https:\/\/www.chromacon.com\/wp-content\/uploads\/2025\/12\/Gemini_Generated_Image_vq3a03vq3a03vq3a-1024x863.jpg 1024w, https:\/\/www.chromacon.com\/wp-content\/uploads\/2025\/12\/Gemini_Generated_Image_vq3a03vq3a03vq3a-768x647.jpg 768w, https:\/\/www.chromacon.com\/wp-content\/uploads\/2025\/12\/Gemini_Generated_Image_vq3a03vq3a03vq3a-1536x1295.jpg 1536w, https:\/\/www.chromacon.com\/wp-content\/uploads\/2025\/12\/Gemini_Generated_Image_vq3a03vq3a03vq3a-2048x1726.jpg 2048w\" sizes=\"(max-width: 2240px) 100vw, 2240px\" \/>                        <\/div>\n\n                                                    <div class=\"block-hero__overlay typo-off\">\n                                <img decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/www.chromacon.com\/wp-content\/uploads\/2026\/05\/Twin-Column-Icon-v2-Photoroom-scaled.png\" class=\"block-hero__overlay-img\" alt=\"\" loading=\"eager\" srcset=\"https:\/\/www.chromacon.com\/wp-content\/uploads\/2026\/05\/Twin-Column-Icon-v2-Photoroom-scaled.png 2560w, https:\/\/www.chromacon.com\/wp-content\/uploads\/2026\/05\/Twin-Column-Icon-v2-Photoroom-300x200.png 300w, https:\/\/www.chromacon.com\/wp-content\/uploads\/2026\/05\/Twin-Column-Icon-v2-Photoroom-1024x683.png 1024w, https:\/\/www.chromacon.com\/wp-content\/uploads\/2026\/05\/Twin-Column-Icon-v2-Photoroom-768x512.png 768w, https:\/\/www.chromacon.com\/wp-content\/uploads\/2026\/05\/Twin-Column-Icon-v2-Photoroom-1536x1024.png 1536w, https:\/\/www.chromacon.com\/wp-content\/uploads\/2026\/05\/Twin-Column-Icon-v2-Photoroom-2048x1365.png 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>                            <\/div>\n                        \n                                                    <div class=\"block-hero__mobile-buttons flex flex-col items-stretch md:items-start gap-[30px]\">\n                                                                    <div class=\"block-hero__mobile-button\">\n                                        <span class=\"c-btn-focus-wrapper\"><a href=\"#contact-form\" class=\"c-btn c-btn--regular c-btn--primary c-btn--light w-full md:w-auto\"><span>Sprechen Sie mit einem Experten<\/span><\/a><\/span>                                    <\/div>\n                                                                                                    <div class=\"block-hero__mobile-button block-hero__mobile-button--secondary\">\n                                        <span class=\"c-btn-focus-wrapper\"><a href=\"https:\/\/www.chromacon.com\/de\/dienstleistungen\/demos-einfuehrungen\/\" class=\"c-btn c-btn--regular c-btn--secondary c-btn--light w-full md:w-auto\"><span>Besuchen Sie unser Applikationslabor<\/span><\/a><\/span>                                    <\/div>\n                                                            <\/div>\n                                                            <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n            <div class=\"w-full h-[75px] bg-gray-50 -mt-[75px]\"><\/div>\n    <\/section><section id=\"block_fa65869c53a8ea85ba91173e7eb97fc5\" class=\"block-text-image py-fluid-6xl bg-gray-50 alignfull  \" style=\"--block-bg-image: url(https:\/\/www.chromacon.com\/wp-content\/themes\/chromacon\/assets\/img\/layout\/block-background-line.svg);\">\n    \n    <section class=\"wrapper-bl-r\">\n                <div class=\"grid grid-cols-1 md:grid-cols-2 gap-fluid-xl md:gap-fluid-4xl-plus items-center\">\n            <div class=\"order-2 md:order-2 md:max-w-[656px]\">\n                                    <h2 class=\"text-h1 md:text-h2 text-primary-800 mb-4 md:mb-6 !mt-0 typo-off\">\n                        Unsere Geschichte                    <\/h2>\n                \n                                    <div class=\"prose prose-lg max-w-none mb-6 md:mb-8 [&#038;_h1]:text-primary-800 [&#038;_h2]:text-primary-800 [&#038;_h3]:text-primary-800 [&#038;_h4]:text-primary-800 [&#038;_h5]:text-primary-800 [&#038;_h6]:text-primary-800\">\n                        <p><strong>ChromaCon<\/strong> begann im Jahr 2006 mit einer Frage: Warum sollte die Aufreinigung der Flaschenhals in der biopharmazeutischen Herstellung sein?<\/p>\n<p>Unsere Gr\u00fcnder, die \u00fcber fundierte Expertise in der Trennungswissenschaft verf\u00fcgen, erkannten, dass die Batch-Chromatographie \u2013 obwohl sie der Industriestandard ist \u2013 erhebliches Verbesserungspotenzial bot.<\/p>\n<p>Ihre Antwort war die kontinuierliche Chromatographie. Durch die Kombination der Vorteile der Gegenstrombewegung mit einem automatisierten zyklischen Betrieb verbesserte dieser Ansatz die Prozess\u00f6konomie drastisch und reduzierte gleichzeitig den Abfall. <\/p>\n<p>Was als Forschungsgruppe begann, entwickelte sich zu einem Unternehmen mit einem einzigartigen Portfolio an Prozesspatenten. Im Jahr 2019 wurde ChromaCon Teil der <strong>YMC<\/strong>-Unternehmensgruppe. <\/p>\n                    <\/div>\n                \n                            <\/div>\n\n                        <div class=\"order-1 md:order-1 typo-off\">\n                                        <img decoding=\"async\" width=\"1024\" height=\"813\" src=\"https:\/\/www.chromacon.com\/wp-content\/uploads\/2026\/04\/Gemini_Generated_Image_5k688u5k688u5k68-e1777219375316-1024x813.jpg\" class=\"w-full h-auto object-cover\" alt=\"\" srcset=\"https:\/\/www.chromacon.com\/wp-content\/uploads\/2026\/04\/Gemini_Generated_Image_5k688u5k688u5k68-e1777219375316-1024x813.jpg 1024w, https:\/\/www.chromacon.com\/wp-content\/uploads\/2026\/04\/Gemini_Generated_Image_5k688u5k688u5k68-e1777219375316-300x238.jpg 300w, https:\/\/www.chromacon.com\/wp-content\/uploads\/2026\/04\/Gemini_Generated_Image_5k688u5k688u5k68-e1777219375316-768x609.jpg 768w, https:\/\/www.chromacon.com\/wp-content\/uploads\/2026\/04\/Gemini_Generated_Image_5k688u5k688u5k68-e1777219375316-1536x1219.jpg 1536w, https:\/\/www.chromacon.com\/wp-content\/uploads\/2026\/04\/Gemini_Generated_Image_5k688u5k688u5k68-e1777219375316.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>                    \n                            <\/div>\n                    <\/div>\n    <\/section>\n\n<\/section><section id=\"block_fbb589c1fc964256fd8a503d5e45901c\" class=\"block-text-image py-fluid-6xl alignfull  \"><div class=\"l-wrap\">\n    \n    <section class=\"\">\n                <div class=\"grid grid-cols-1 md:grid-cols-2 gap-fluid-xl md:gap-fluid-4xl-plus items-center\">\n            <div class=\"order-2 md:order-1 md:max-w-[656px]\">\n                                    <h2 class=\"text-h1 md:text-h2 text-primary-800 mb-4 md:mb-6 !mt-0 typo-off\">\n                        Unsere Mission                    <\/h2>\n                \n                                    <div class=\"prose prose-lg max-w-none mb-6 md:mb-8 [&#038;_h1]:text-primary-800 [&#038;_h2]:text-primary-800 [&#038;_h3]:text-primary-800 [&#038;_h4]:text-primary-800 [&#038;_h5]:text-primary-800 [&#038;_h6]:text-primary-800\">\n                        <p>Unser Ziel ist es, biopharmazeutischen Teams zu einer intelligenteren Aufreinigung zu verhelfen.<\/p>\n<p>Das bedeutet, L\u00f6sungen f\u00fcr die kontinuierliche Chromatographie bereitzustellen, die herk\u00f6mmliche Methoden nicht nur geringf\u00fcgig, sondern substanziell \u00fcbertreffen. Unser Ansatz der kontinuierlichen Herstellung erm\u00f6glicht im Vergleich zur traditionellen Batch-Verarbeitung Reduzierungen der Kapital- und Betriebskosten um 30\u201350 %, h\u00f6here Ausbeuten, eine bessere Harzausnutzung sowie einen verringerten Bedarf an In-Prozess-Kontrollen (IPCs) und Eluentenverbrauch. Er liefert mehr Produkt aus demselben Ausgangsmaterial \u2013 oder die gleiche Produktmenge mit deutlich weniger Einsatzstoffen.  <\/p>\n<p>Ganz gleich, ob Sie mit monoklonalen Antik\u00f6rpern, Oligonukleotiden, Peptiden oder neuen Modalit\u00e4ten wie mRNA und viralen Vektoren arbeiten \u2013 unser Ziel bleibt dasselbe: Ihnen die Werkzeuge und das Fachwissen zur Verf\u00fcgung zu stellen, um den Schritt von der Entwicklung zur Herstellung mit Zuversicht zu meistern und letztendlich wirksame Behandlungen zu den Patienten zu bringen, die sie ben\u00f6tigen.<\/p>\n                    <\/div>\n                \n                            <\/div>\n\n                        <div class=\"order-1 md:order-2 typo-off\">\n                                        <img decoding=\"async\" width=\"1024\" height=\"800\" src=\"https:\/\/www.chromacon.com\/wp-content\/uploads\/2026\/01\/Gemini_Generated_Image_5n8qac5n8qac5n8q-1024x800.png\" class=\"w-full h-auto object-cover\" alt=\"\" \/>                    \n                            <\/div>\n                    <\/div>\n    <\/section>\n\n<\/div><\/section><section id=\"block_de0d128c77d795bad7b2914e35650819\" class=\"block-text-image py-fluid-6xl bg-gray-50 alignfull  \" style=\"--block-bg-image: url(https:\/\/www.chromacon.com\/wp-content\/themes\/chromacon\/assets\/img\/layout\/block-background-line.svg);\">\n    \n    <section class=\"wrapper-bl-r\">\n                <div class=\"grid grid-cols-1 md:grid-cols-2 gap-fluid-xl md:gap-fluid-4xl-plus items-center\">\n            <div class=\"order-2 md:order-2 md:max-w-[656px]\">\n                                    <h2 class=\"text-h1 md:text-h2 text-primary-800 mb-4 md:mb-6 !mt-0 typo-off\">\n                        Unsere Technologie                    <\/h2>\n                \n                                    <div class=\"prose prose-lg max-w-none mb-6 md:mb-8 [&#038;_h1]:text-primary-800 [&#038;_h2]:text-primary-800 [&#038;_h3]:text-primary-800 [&#038;_h4]:text-primary-800 [&#038;_h5]:text-primary-800 [&#038;_h6]:text-primary-800\">\n                        <p>CaptureSMB\u00ae optimiert Capture-Schritte durch den Betrieb von zwei S\u00e4ulen in einer synchronisierten Sequenz, wodurch die Beladungskapazit\u00e4t des Harzes maximiert und der Pufferverbrauch minimiert wird. Das Ergebnis: deutlich niedrigere Herstellkosten f\u00fcr hochwertige Molek\u00fcle. <\/p>\n<p>MCSGP bew\u00e4ltigt zusammen mit der dynamischen Prozesssteuerung AutoPeak\u00ae komplexe Polishing-Trennungen, bei denen herk\u00f6mmliche Methoden an ihre Grenzen sto\u00dfen. Es erzielt gleichzeitig hohe Reinheit und Ausbeute \u2013 besonders wertvoll bei nah verwandten Verunreinigungen, die mit traditioneller Chromatographie nicht sauber getrennt werden k\u00f6nnen. <\/p>\n<p>Diese Prozesse laufen auf unserer Contichrom\u00ae-Plattform. Der Contichrom CUBE \u2013 ein Doppel-S\u00e4ulen-FPLC-Entwicklungssystem \u2013 erm\u00f6glicht es Teams, mehrere kontinuierliche Prozesse zu evaluieren und den besten Ansatz f\u00fcr jede spezifische Trennaufgabe auszuw\u00e4hlen. Auf dem CUBE entwickelte Prozesse lassen sich direkt auf unsere GMP-f\u00e4higen Produktionssystemlinien, den Contichrom PILOT &amp; TWIN, skalieren. Unsere ChromIQ\u00ae-Software bietet dabei eine intuitive Steuerung und ein umfassendes Datenmanagement.   <\/p>\n                    <\/div>\n                \n                                    <span class=\"c-btn-focus-wrapper\"><a href=\"https:\/\/www.chromacon.com\/de\/technologieuebersicht\/\" class=\"c-btn c-btn--regular c-btn--secondary c-btn--light\"><span>Erfahren Sie mehr \u00fcber Contichrom\u00ae-Technologien<\/span><\/a><\/span>                            <\/div>\n\n                        <div class=\"order-1 md:order-1 typo-off\">\n                                        <img decoding=\"async\" width=\"1024\" height=\"816\" src=\"https:\/\/www.chromacon.com\/wp-content\/uploads\/2026\/01\/Gemini_Generated_Image_bmdontbmdontbmdo-e1768228311198-1024x816.jpg\" class=\"w-full h-auto object-cover\" alt=\"\" srcset=\"https:\/\/www.chromacon.com\/wp-content\/uploads\/2026\/01\/Gemini_Generated_Image_bmdontbmdontbmdo-e1768228311198-1024x816.jpg 1024w, https:\/\/www.chromacon.com\/wp-content\/uploads\/2026\/01\/Gemini_Generated_Image_bmdontbmdontbmdo-e1768228311198-300x239.jpg 300w, https:\/\/www.chromacon.com\/wp-content\/uploads\/2026\/01\/Gemini_Generated_Image_bmdontbmdontbmdo-e1768228311198-768x612.jpg 768w, https:\/\/www.chromacon.com\/wp-content\/uploads\/2026\/01\/Gemini_Generated_Image_bmdontbmdontbmdo-e1768228311198-1536x1224.jpg 1536w, https:\/\/www.chromacon.com\/wp-content\/uploads\/2026\/01\/Gemini_Generated_Image_bmdontbmdontbmdo-e1768228311198.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>                    \n                            <\/div>\n                    <\/div>\n    <\/section>\n\n<\/section><section id=\"block_1557033eb2ba6b1abb803b4363230271\" class=\"block-text-image py-fluid-6xl alignfull  \"><div class=\"l-wrap\">\n    \n    <section class=\"\">\n                <div class=\"grid grid-cols-1 md:grid-cols-2 gap-fluid-xl md:gap-fluid-4xl-plus items-center\">\n            <div class=\"order-2 md:order-1 md:max-w-[656px]\">\n                                    <h2 class=\"text-h1 md:text-h2 text-primary-800 mb-4 md:mb-6 !mt-0 typo-off\">\n                        Wie wir arbeiten                    <\/h2>\n                \n                                    <div class=\"prose prose-lg max-w-none mb-6 md:mb-8 [&#038;_h1]:text-primary-800 [&#038;_h2]:text-primary-800 [&#038;_h3]:text-primary-800 [&#038;_h4]:text-primary-800 [&#038;_h5]:text-primary-800 [&#038;_h6]:text-primary-800\">\n                        <p>Wir sind kein Unternehmen, das Ger\u00e4te ausliefert und dann verschwindet. Die kontinuierliche Chromatographie stellt einen bedeutenden Wandel in der Aufreinigung dar, und wir setzen uns daf\u00fcr ein, dass unsere Kunden damit erfolgreich sind. <\/p>\n<p>Dieses Engagement zeigt sich auf verschiedene Weise: Machbarkeitsstudien zur Pr\u00fcfung, ob unsere Technologie zu Ihrer spezifischen Herausforderung passt, fortschrittliche Prozessmodellierung zur Optimierung vor dem Lauf, Systemmiete zur Evaluierung und praxisnahe Workshops zum Aufbau der Expertise Ihres Teams. Wir bieten pr\u00e4ventive Wartung und Reparaturservices an, um Ihre Systeme f\u00fcr die kontinuierliche Chromatographie in bestm\u00f6glichem Zustand zu halten. Unsere ISO-Zertifizierung spiegelt die Qualit\u00e4tsstandards wider, die wir bei Systemdesign, Fertigung und laufendem Support einhalten.  <\/p>\n<p>Wenn Sie bereit f\u00fcr das Scale-up sind, gew\u00e4hrleistet unsere Partnerschaft mit <a href=\"https:\/\/www.ymcamerica.com\/contichrom-twin-hplc\/\" target=\"_blank\" rel=\"noopener\">YMC America<\/a> einen nahtlosen \u00dcbergang von der Entwicklung im Laborma\u00dfstab zur GMP-Fertigung. Wir betrachten die Beziehung als echte Partnerschaft \u2013 Ihre Trennherausforderung wird zu unserer gemeinsamen Aufgabe. <\/p>\n                    <\/div>\n                \n                            <\/div>\n\n                        <div class=\"order-1 md:order-2 typo-off\">\n                                        <img decoding=\"async\" width=\"1024\" height=\"800\" src=\"https:\/\/www.chromacon.com\/wp-content\/uploads\/2026\/01\/Gemini_Generated_Image_us4i71us4i71us4i-1024x800.png\" class=\"w-full h-auto object-cover\" alt=\"\" srcset=\"https:\/\/www.chromacon.com\/wp-content\/uploads\/2026\/01\/Gemini_Generated_Image_us4i71us4i71us4i-1024x800.png 1024w, https:\/\/www.chromacon.com\/wp-content\/uploads\/2026\/01\/Gemini_Generated_Image_us4i71us4i71us4i-300x234.png 300w, https:\/\/www.chromacon.com\/wp-content\/uploads\/2026\/01\/Gemini_Generated_Image_us4i71us4i71us4i-768x600.png 768w, https:\/\/www.chromacon.com\/wp-content\/uploads\/2026\/01\/Gemini_Generated_Image_us4i71us4i71us4i.png 1168w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>                    \n                            <\/div>\n                    <\/div>\n    <\/section>\n\n<\/div><\/section><section id=\"block_4f1daa27dd4a904cf033ae3bd37b682f\" class=\"block-text-image py-fluid-6xl bg-gray-50 alignfull  \" style=\"--block-bg-image: url(https:\/\/www.chromacon.com\/wp-content\/themes\/chromacon\/assets\/img\/layout\/block-background-line.svg);\">\n    \n    <section class=\"wrapper-bl-r\">\n                <div class=\"grid grid-cols-1 md:grid-cols-2 gap-fluid-xl md:gap-fluid-4xl-plus items-center\">\n            <div class=\"order-2 md:order-2 md:max-w-[656px]\">\n                                    <h2 class=\"text-h1 md:text-h2 text-primary-800 mb-4 md:mb-6 !mt-0 typo-off\">\n                        Blick in die Zukunft                    <\/h2>\n                \n                                    <div class=\"prose prose-lg max-w-none mb-6 md:mb-8 [&#038;_h1]:text-primary-800 [&#038;_h2]:text-primary-800 [&#038;_h3]:text-primary-800 [&#038;_h4]:text-primary-800 [&#038;_h5]:text-primary-800 [&#038;_h6]:text-primary-800\">\n                        <p>Die biopharmazeutische Landschaft ver\u00e4ndert sich. Molek\u00fcle werden komplexer. Die Anforderungen an die Herstellung steigen. Der Druck zur Nachhaltigkeit ist real.   <\/p>\n<p>Wir sehen die kontinuierliche Chromatographie als zentrales Element zur Bew\u00e4ltigung dieser Herausforderungen \u2013 nicht als Nischentechnik, sondern als k\u00fcnftigen Standard f\u00fcr eine effiziente, nachhaltige Aufreinigung. Die Wirtschaftlichkeit spricht daf\u00fcr: 30\u201350 % niedrigere Betriebskosten machen die kontinuierliche Fertigung immer attraktiver, w\u00e4hrend die Branche die Produktion von Biologika und chemischen Arzneimitteln der n\u00e4chsten Generation ausweitet. <\/p>\n<p>Unsere laufende Entwicklungsarbeit konzentriert sich darauf, unsere Technologien auf neue Modalit\u00e4ten auszuweiten und gleichzeitig die Leistung f\u00fcr etablierte Therapieklassen weiter zu verfeinern. Das Ziel hat sich seit 2006 nicht ge\u00e4ndert: eine effizientere und nachhaltigere Produktion von Medikamenten zu erm\u00f6glichen, die das Leben verbessern. Wir stehen erst am Anfang.  <\/p>\n                    <\/div>\n                \n                            <\/div>\n\n                        <div class=\"order-1 md:order-1 typo-off\">\n                                        <img decoding=\"async\" width=\"1024\" height=\"806\" src=\"https:\/\/www.chromacon.com\/wp-content\/uploads\/2026\/03\/Gemini_Generated_Image_1m7pjt1m7pjt1m7p-scaled-e1774348895815-1024x806.png\" class=\"w-full h-auto object-cover\" alt=\"\" srcset=\"https:\/\/www.chromacon.com\/wp-content\/uploads\/2026\/03\/Gemini_Generated_Image_1m7pjt1m7pjt1m7p-scaled-e1774348895815-1024x806.png 1024w, https:\/\/www.chromacon.com\/wp-content\/uploads\/2026\/03\/Gemini_Generated_Image_1m7pjt1m7pjt1m7p-scaled-e1774348895815-300x236.png 300w, https:\/\/www.chromacon.com\/wp-content\/uploads\/2026\/03\/Gemini_Generated_Image_1m7pjt1m7pjt1m7p-scaled-e1774348895815-768x605.png 768w, https:\/\/www.chromacon.com\/wp-content\/uploads\/2026\/03\/Gemini_Generated_Image_1m7pjt1m7pjt1m7p-scaled-e1774348895815-1536x1209.png 1536w, https:\/\/www.chromacon.com\/wp-content\/uploads\/2026\/03\/Gemini_Generated_Image_1m7pjt1m7pjt1m7p-scaled-e1774348895815.png 1810w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>                    \n                            <\/div>\n                    <\/div>\n    <\/section>\n\n<\/section>\n<h2 class=\"wp-block-heading has-heading-h-2-font-size\">Das YMC-\u00d6kosystem: Systeme, Medien und globaler Support<\/h2>\n\n<div class=\"wp-block-columns alignwide is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><section id=\"block_a169a2a16562234a63c2021476270d0f\" class=\"block-card alignfull  \"><div class=\"l-wrap\">\n    <div class=\"c-card\">\n    \n            <div class=\"c-card__image size-full\">\n                            <img decoding=\"async\" width=\"682\" height=\"379\" src=\"https:\/\/www.chromacon.com\/wp-content\/uploads\/2025\/11\/Rectangle-4485-1.jpg\" class=\"c-card__img\" alt=\"Teil der YMC Group\" srcset=\"https:\/\/www.chromacon.com\/wp-content\/uploads\/2025\/11\/Rectangle-4485-1.jpg 682w, https:\/\/www.chromacon.com\/wp-content\/uploads\/2025\/11\/Rectangle-4485-1-300x167.jpg 300w\" sizes=\"(max-width: 682px) 100vw, 682px\" \/>                    <\/div>\n        \n    <div class=\"c-card__content p-fluid-l\">\n        \n                    <h3 class=\"c-card__title heading--h3\">\n                                    Teil der YMC Group                            <\/h3>\n                \n                    <p class=\"c-card__description\">\n                YMC ChromaCon ist das Kompetenzzentrum f\u00fcr kontinuierliche Chromatographie innerhalb der YMC-Gruppe. Unsere Schwestergesellschaften bringen jahrzehntelange Expertise in Chromatographiemedien, S\u00e4ulen und analytischen Systemen ein \u2013 gemeinsam liefern wir End-to-End-Aufreinigungsl\u00f6sungen von der Entwicklung im Laborma\u00dfstab bis zur vollst\u00e4ndigen GMP-Fertigung.             <\/p>\n                \n                    <div class=\"c-card__button\">\n                <span class=\"c-btn-focus-wrapper\"><a href=\"\" class=\"c-btn c-btn--regular c-btn--secondary c-btn--light\" target=\"_blank\" rel=\"noopener noreferrer\"><span>\u00dcber die YMC-Gruppe<\/span><\/a><\/span>            <\/div>\n                \n    <\/div>\n\n<\/div>\n\n    <\/div><\/section><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><section id=\"block_6cb4f537f1fc0310713b5a01268e4274\" class=\"block-card alignfull  \"><div class=\"l-wrap\">\n    <div class=\"c-card\">\n    \n            <div class=\"c-card__image size-full\">\n                            <a href=\"https:\/\/ymc.eu\/home.html\" class=\"c-card__image-link\" target=\"_blank\">\n                    <img decoding=\"async\" width=\"1024\" height=\"591\" src=\"https:\/\/www.chromacon.com\/wp-content\/uploads\/2026\/04\/YMC-Europe-Logo-1024x591.png\" class=\"c-card__img\" alt=\"S\u00e4ulen &amp; Harze entdecken\" srcset=\"https:\/\/www.chromacon.com\/wp-content\/uploads\/2026\/04\/YMC-Europe-Logo-1024x591.png 1024w, https:\/\/www.chromacon.com\/wp-content\/uploads\/2026\/04\/YMC-Europe-Logo-300x173.png 300w, https:\/\/www.chromacon.com\/wp-content\/uploads\/2026\/04\/YMC-Europe-Logo-768x443.png 768w, https:\/\/www.chromacon.com\/wp-content\/uploads\/2026\/04\/YMC-Europe-Logo.png 1467w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>                <\/a>\n                    <\/div>\n        \n    <div class=\"c-card__content p-fluid-l\">\n        \n                    <h3 class=\"c-card__title heading--h3\">\n                                    <a href=\"https:\/\/ymc.eu\/home.html\" class=\"c-card__title-link !no-underline\" target=\"_blank\">\n                        S\u00e4ulen &amp; Harze entdecken                    <\/a>\n                            <\/h3>\n                \n                    <p class=\"c-card__description\">\n                Suchen Sie nach Chromatographiemedien, gepackten S\u00e4ulen oder Bulk-Harzen f\u00fcr Ihr Contichrom\u00ae-System? Die YMC Europe GmbH \u2013 unsere Schwestergesellschaft \u2013 bietet eines der breitesten Portfolios an Chromatographiemedien in der Branche an, inklusive umfassender technischer Unterst\u00fctzung f\u00fcr die Methodenentwicklung und das Scale-up.             <\/p>\n                \n                    <div class=\"c-card__button\">\n                <span class=\"c-btn-focus-wrapper\"><a href=\"https:\/\/ymc.eu\/home.html\" class=\"c-btn c-btn--regular c-btn--secondary c-btn--light\" target=\"_blank\" rel=\"noopener noreferrer\"><span>YMC Europe besuchen<\/span><\/a><\/span>            <\/div>\n                \n    <\/div>\n\n<\/div>\n\n    <\/div><\/section><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><section id=\"block_c917f17572b0224ee17a9ef22ad195df\" class=\"block-card alignfull  \"><div class=\"l-wrap\">\n    <div class=\"c-card\">\n    \n            <div class=\"c-card__image size-full\">\n                            <a href=\"https:\/\/www.chromacon.com\/de\/vertriebspartner\/\" class=\"c-card__image-link\">\n                    <img decoding=\"async\" width=\"1024\" height=\"325\" src=\"https:\/\/www.chromacon.com\/wp-content\/uploads\/2025\/12\/Union-1024x325.png\" class=\"c-card__img\" alt=\"Globale Reichweite, lokaler Support\" srcset=\"https:\/\/www.chromacon.com\/wp-content\/uploads\/2025\/12\/Union-1024x325.png 1024w, https:\/\/www.chromacon.com\/wp-content\/uploads\/2025\/12\/Union-300x95.png 300w, https:\/\/www.chromacon.com\/wp-content\/uploads\/2025\/12\/Union-768x244.png 768w, https:\/\/www.chromacon.com\/wp-content\/uploads\/2025\/12\/Union.png 1440w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>                <\/a>\n                    <\/div>\n        \n    <div class=\"c-card__content p-fluid-l\">\n        \n                    <h3 class=\"c-card__title heading--h3\">\n                                    <a href=\"https:\/\/www.chromacon.com\/de\/vertriebspartner\/\" class=\"c-card__title-link !no-underline\">\n                        Globale Reichweite, lokaler Support                    <\/a>\n                            <\/h3>\n                \n                    <p class=\"c-card__description\">\n                Kunden weltweit vertrauen auf die Contichrom\u00ae-Plattform. Durch die YMC-Gruppe und unser Netzwerk spezialisierter Distributoren erhalten Sie lokales Fachwissen, schnelle Service-Reaktionszeiten und direkten Zugang zu unseren Systemen \u2013 wo auch immer Sie t\u00e4tig sind.             <\/p>\n                \n                    <div class=\"c-card__button\">\n                <span class=\"c-btn-focus-wrapper\"><a href=\"https:\/\/www.chromacon.com\/de\/vertriebspartner\/\" class=\"c-btn c-btn--regular c-btn--secondary c-btn--light\"><span>Vertriebspartner finden<\/span><\/a><\/span>            <\/div>\n                \n    <\/div>\n\n<\/div>\n\n    <\/div><\/section><\/div>\n<\/div>\n<section id=\"block_4480b795b0ce68cca601930e3563a6b0\" class=\"block-team py-fluid-xl md:py-fluid-5xl bg-gray-50 typo-off alignfull  \"><div class=\"l-wrap\">\n            <div class=\"block-team__header mb-fluid-xs md:mb-fluid-4xl\">\n                            <h2 class=\"heading-h1 text-center text-primary-800 !mt-0 mb-fluid-m\">Lernen Sie das Team kennen<\/h2>\n                                        <p class=\"text-m leading-body-text text-center\">\n                    Experten f\u00fcr kontinuierliche Chromatographie \u2013 engagiert f\u00fcr Ihre Ziele.                <\/p>\n                    <\/div>\n    \n            <div class=\"block-team__grid grid grid-cols-1 sm:grid-cols-2 lg:grid-cols-3 gap-fluid-2xs md:gap-x-fluid-s md:gap-y-fluid-m\">\n                            <div class=\"block-team__card relative aspect-[9\/10] overflow-hidden group\" data-member-id=\"team-member-0\">\n                                            <div class=\"block-team__card-image absolute inset-0\">\n                            <img decoding=\"async\" width=\"819\" height=\"1024\" src=\"https:\/\/www.chromacon.com\/wp-content\/uploads\/2026\/02\/CC_TM_v1-819x1024.jpeg\" class=\"!size-full object-cover\" alt=\"Dr. Thomas M\u00fcller-Sp\u00e4th  \" srcset=\"https:\/\/www.chromacon.com\/wp-content\/uploads\/2026\/02\/CC_TM_v1-819x1024.jpeg 819w, https:\/\/www.chromacon.com\/wp-content\/uploads\/2026\/02\/CC_TM_v1-240x300.jpeg 240w, https:\/\/www.chromacon.com\/wp-content\/uploads\/2026\/02\/CC_TM_v1-768x960.jpeg 768w, https:\/\/www.chromacon.com\/wp-content\/uploads\/2026\/02\/CC_TM_v1-1229x1536.jpeg 1229w, https:\/\/www.chromacon.com\/wp-content\/uploads\/2026\/02\/CC_TM_v1-1639x2048.jpeg 1639w, https:\/\/www.chromacon.com\/wp-content\/uploads\/2026\/02\/CC_TM_v1-scaled.jpeg 2048w\" sizes=\"(max-width: 819px) 100vw, 819px\" \/>                        <\/div>\n                    \n                    <div class=\"block-team__card-collapsed absolute inset-0 bg-transparent flex flex-col justify-end transition-opacity duration-300\" data-state=\"collapsed\">\n                        <div class=\"p-6\">\n                            <div class=\"flex items-start\">\n                                <div class=\"block-team__collapsed-text text-white relative pl-5 space-y-1.5\">\n                                                                            <span class=\"text-h3 leading-h4 md:text-h4 md:leading-h4 block\">Dr. Thomas M\u00fcller-Sp\u00e4th  <\/span>\n                                                                                                                <span class=\"text-s md:text-m block\">CEO &amp; Mitgr\u00fcnder<\/span>\n                                                                    <\/div>\n                            <\/div>\n                            <button\n                                class=\"block-team__card-expand-btn absolute bottom-[24px] right-[24px] md:bottom-[28px] md:right-[28px] w-[50px] h-[50px] md:w-[57px] md:h-[57px] rounded-full bg-secondary-700 text-white flex items-center justify-center transition-colors box-border cursor-pointer\"\n                                aria-label=\"Dr. Thomas M\u00fcller-Sp\u00e4th  -Details erweitern\"\n                                data-action=\"expand\">\n                                <span class=\"text-2xl font-light\">+<\/span>\n                            <\/button>\n                        <\/div>\n                    <\/div>\n\n                    <div class=\"block-team__card-expanded absolute inset-0 bg-secondary-700 text-white overflow-hidden flex flex-col transition-opacity duration-300 opacity-0 pointer-events-none\" data-state=\"expanded\">\n                        <button\n                            class=\"block-team__card-close-btn absolute bottom-[24px] right-[24px] md:bottom-[28px] md:right-[28px] w-[50px] h-[50px] md:w-[57px] md:h-[57px] rounded-full bg-secondary-700 border border-white box-border text-white flex items-center justify-center transition-colors z-10 cursor-pointer\"\n                            aria-label=\"Schlie\u00dfen\"\n                            data-action=\"close\">\n                            <span class=\"text-2xl font-light leading-[0] block\">\u00d7<\/span>\n                        <\/button>\n\n                        <div class=\"block-team__card-expanded-inner flex-1 flex flex-col overflow-y-auto p-fluid-m pb-[28px] gap-y-fluid-xs\">\n\n                            <div class=\"block-team__collapsed-text text-white relative pl-5 space-y-1.5 hidden md:block\">\n                                                                    <span class=\"text-h4 leading-h4 block\">Dr. Thomas M\u00fcller-Sp\u00e4th  <\/span>\n                                                                                                    <span class=\"text-s md:text-m block\">CEO &amp; Mitgr\u00fcnder<\/span>\n                                                            <\/div>\n\n                                                            <div class=\"flex-shrink-0\">\n                                    <p class=\"text-m text-white\">Dr. Thomas M\u00fcller-Sp\u00e4th steht an vorderster Front des Wandels von der Batch- zur kontinuierlichen Fertigung in der Biopharma-Branche. Als CEO von YMC ChromaCon kombiniert er fundierte Expertise im Chemieingenieurwesen mit einer strategischen Vision zur Industrialisierung von Technologien zur Prozessintensivierung.<br \/><br \/>\r\nWissenschaftliche Wurzeln &amp; die Geburtsstunde von MCSGP:<br \/><br \/>\r\nThomas promovierte in Chemieingenieurwesen an der Eidgen\u00f6ssischen Technischen Hochschule (ETH Z\u00fcrich), wo er seine Doktorarbeit in der renommierten Morbidelli-Gruppe verfasste. Hier half er bei der Entwicklung der Multi-column Counter-current Solvent Gradient Purification (MCSGP) \u2013 einer Technologie, die heute als Benchmark f\u00fcr die L\u00f6sung schwieriger Kompromisse bei der Aufreinigung gilt.<br \/><br \/>\r\nAusbildung: <br \/><br \/>\r\nPromotion, ETH Z\u00fcrich; Dipl.-Ing., Technische Universit\u00e4t Hamburg; Austauschstudium, University of California, Berkeley.<br \/><br \/>\r\nForschungsschwerpunkte: <br \/><br \/>\r\nKontinuierliche Chromatographie, Prozessmodellierung und die Aufreinigung komplexer Biomolek\u00fcle.<br \/><br \/>\r\nVom Konzept zum Industriestandard:<br \/><br \/>\r\nMit der Mitbegr\u00fcndung von ChromaCon im Jahr 2006 war Thomas ma\u00dfgeblich daran beteiligt, komplexe akademische Konzepte in die robuste Contichrom\u00ae-Hardwareplattform zu \u00fcberf\u00fchren. Er hat die Technologie von einer Laborkuriosit\u00e4t zu einer GMP-f\u00e4higen Fertigungsl\u00f6sung gef\u00fchrt, die von f\u00fchrenden Pharmaunternehmen weltweit eingesetzt wird. Seine Arbeit war entscheidend f\u00fcr den Nachweis, dass kontinuierliche Prozesse (wie CaptureSMB f\u00fcr mAbs und MCSGP f\u00fcr Peptide\/Oligonukleotide) die Investitions- und Betriebskosten (CAPEX\/OPEX) erheblich senken und gleichzeitig die Produktqualit\u00e4t verbessern k\u00f6nnen.<br \/><br \/>\r\nVordenkerrolle:<br \/><br \/>\r\nThomas ist weiterhin ein aktives Mitglied der wissenschaftlichen Gemeinschaft. Er ist Erfinder mehrerer Kernpatente im Bereich der kontinuierlichen Verarbeitung und hat \u00fcber 30 wissenschaftliche Publikationen verfasst. Er ist regelm\u00e4\u00dfiger Sprecher auf bedeutenden Branchenkonferenzen (TIDES, SPICA, PREP), wo er sich f\u00fcr die wirtschaftlichen und technischen Vorteile des kontinuierlichen Downstream-Processings einsetzt.      <br \/><br \/>\r\n<\/p>\n                                <\/div>\n                            \n                            <div class=\"flex gap-3 flex-shrink-0\">\n                                                                    <a\n                                        href=\"https:\/\/www.linkedin.com\/in\/thomas-m%C3%BCller-sp%C3%A4th-12a44237\/\"\n                                        target=\"_blank\"\n                                        rel=\"noopener noreferrer\"\n                                        class=\"w-[50px] h-[50px] md:w-[61px] md:h-[61px] rounded-full bg-transparent border border-white\/20 box-border text-white flex items-center justify-center transition-colors flex-shrink-0 cursor-pointer\"\n                                        aria-label=\"LinkedIn-Profil f\u00fcr Dr. Thomas M\u00fcller-Sp\u00e4th  \">\n                                        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 448 512\" class=\"svg-inline--fa w-[50px] h-[50px] md:w-[61px] md:h-[61px]\" role=\"img\" aria-hidden=\"true\" style=\"color:currentColor\"><!--! Font Awesome Free 6.7.2 by @fontawesome - https:\/\/fontawesome.com License - https:\/\/fontawesome.com\/license\/free (Icons: CC BY 4.0, Fonts: SIL OFL 1.1, Code: MIT License) Copyright 2024 Fonticons, Inc. --><path d=\"M416 32H31.9C14.3 32 0 46.5 0 64.3v383.4C0 465.5 14.3 480 31.9 480H416c17.6 0 32-14.5 32-32.3V64.3c0-17.8-14.4-32.3-32-32.3zM135.4 416H69V202.2h66.5V416zm-33.2-243c-21.3 0-38.5-17.3-38.5-38.5S80.9 96 102.2 96c21.2 0 38.5 17.3 38.5 38.5 0 21.3-17.2 38.5-38.5 38.5zm282.1 243h-66.4V312c0-24.8-.5-56.7-34.5-56.7-34.6 0-39.9 27-39.9 54.9V416h-66.4V202.2h63.7v29.2h.9c8.9-16.8 30.6-34.5 62.9-34.5 67.2 0 79.7 44.3 79.7 101.9V416z\" fill=\"currentColor\"><\/path><\/svg>\n                                    <\/a>\n                                \n                                                                    <span data-email=\"info@chromacon.com\">\n                                        <a\n                                            href=\"mailto:info@chromacon.com\"\n                                            class=\"w-[50px] h-[50px] md:w-[61px] md:h-[61px] rounded-full bg-transparent border border-white\/20 box-border text-white flex items-center justify-center transition-colors flex-shrink-0 cursor-pointer\"\n                                            aria-label=\"E-Mail Dr. Thomas M\u00fcller-Sp\u00e4th  \">\n                                            <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa w-[50px] h-[50px] md:w-[61px] md:h-[61px]\" role=\"img\" aria-hidden=\"true\" style=\"color:currentColor\"><!--! Font Awesome Free 6.7.2 by @fontawesome - https:\/\/fontawesome.com License - https:\/\/fontawesome.com\/license\/free (Icons: CC BY 4.0, Fonts: SIL OFL 1.1, Code: MIT License) Copyright 2024 Fonticons, Inc. --><path d=\"M48 64C21.5 64 0 85.5 0 112c0 15.1 7.1 29.3 19.2 38.4L236.8 313.6c11.4 8.5 27 8.5 38.4 0L492.8 150.4c12.1-9.1 19.2-23.3 19.2-38.4c0-26.5-21.5-48-48-48L48 64zM0 176L0 384c0 35.3 28.7 64 64 64l384 0c35.3 0 64-28.7 64-64l0-208L294.4 339.2c-22.8 17.1-54 17.1-76.8 0L0 176z\" fill=\"currentColor\"><\/path><\/svg>\n                                        <\/a>\n                                    <\/span>\n                                                            <\/div>\n                        <\/div>\n                    <\/div>\n                <\/div>\n                            <div class=\"block-team__card relative aspect-[9\/10] overflow-hidden group\" data-member-id=\"team-member-1\">\n                                            <div class=\"block-team__card-image absolute inset-0\">\n                            <img decoding=\"async\" width=\"819\" height=\"1024\" src=\"https:\/\/www.chromacon.com\/wp-content\/uploads\/2026\/02\/CC_L_v1-819x1024.jpg\" class=\"!size-full object-cover\" alt=\"Dr. Lars Aumann\" srcset=\"https:\/\/www.chromacon.com\/wp-content\/uploads\/2026\/02\/CC_L_v1-819x1024.jpg 819w, https:\/\/www.chromacon.com\/wp-content\/uploads\/2026\/02\/CC_L_v1-240x300.jpg 240w, https:\/\/www.chromacon.com\/wp-content\/uploads\/2026\/02\/CC_L_v1-768x960.jpg 768w, https:\/\/www.chromacon.com\/wp-content\/uploads\/2026\/02\/CC_L_v1-1229x1536.jpg 1229w, https:\/\/www.chromacon.com\/wp-content\/uploads\/2026\/02\/CC_L_v1-1639x2048.jpg 1639w, https:\/\/www.chromacon.com\/wp-content\/uploads\/2026\/02\/CC_L_v1-scaled.jpg 2048w\" sizes=\"(max-width: 819px) 100vw, 819px\" \/>                        <\/div>\n                    \n                    <div class=\"block-team__card-collapsed absolute inset-0 bg-transparent flex flex-col justify-end transition-opacity duration-300\" data-state=\"collapsed\">\n                        <div class=\"p-6\">\n                            <div class=\"flex items-start\">\n                                <div class=\"block-team__collapsed-text text-white relative pl-5 space-y-1.5\">\n                                                                            <span class=\"text-h3 leading-h4 md:text-h4 md:leading-h4 block\">Dr. Lars Aumann<\/span>\n                                                                                                                <span class=\"text-s md:text-m block\">CTO &amp; Mitbegr\u00fcnder<\/span>\n                                                                    <\/div>\n                            <\/div>\n                            <button\n                                class=\"block-team__card-expand-btn absolute bottom-[24px] right-[24px] md:bottom-[28px] md:right-[28px] w-[50px] h-[50px] md:w-[57px] md:h-[57px] rounded-full bg-secondary-700 text-white flex items-center justify-center transition-colors box-border cursor-pointer\"\n                                aria-label=\"Dr. Lars Aumann-Details erweitern\"\n                                data-action=\"expand\">\n                                <span class=\"text-2xl font-light\">+<\/span>\n                            <\/button>\n                        <\/div>\n                    <\/div>\n\n                    <div class=\"block-team__card-expanded absolute inset-0 bg-secondary-700 text-white overflow-hidden flex flex-col transition-opacity duration-300 opacity-0 pointer-events-none\" data-state=\"expanded\">\n                        <button\n                            class=\"block-team__card-close-btn absolute bottom-[24px] right-[24px] md:bottom-[28px] md:right-[28px] w-[50px] h-[50px] md:w-[57px] md:h-[57px] rounded-full bg-secondary-700 border border-white box-border text-white flex items-center justify-center transition-colors z-10 cursor-pointer\"\n                            aria-label=\"Schlie\u00dfen\"\n                            data-action=\"close\">\n                            <span class=\"text-2xl font-light leading-[0] block\">\u00d7<\/span>\n                        <\/button>\n\n                        <div class=\"block-team__card-expanded-inner flex-1 flex flex-col overflow-y-auto p-fluid-m pb-[28px] gap-y-fluid-xs\">\n\n                            <div class=\"block-team__collapsed-text text-white relative pl-5 space-y-1.5 hidden md:block\">\n                                                                    <span class=\"text-h4 leading-h4 block\">Dr. Lars Aumann<\/span>\n                                                                                                    <span class=\"text-s md:text-m block\">CTO &amp; Mitbegr\u00fcnder<\/span>\n                                                            <\/div>\n\n                                                            <div class=\"flex-shrink-0\">\n                                    <p class=\"text-m text-white\">Der Architekt intelligenter Aufreinigung. Als Chief Scientific Officer leitet Dr. Lars Aumann die Entwicklung der Software- und Prozesssteuerungsstrategien, die die Systeme von ChromaCon antreiben. Er ist verantwortlich f\u00fcr die \u00dcbersetzung komplexer chromatographischer Theorie in benutzerfreundliche, automatisierte Werkzeuge, die es der Contichrom\u00ae-Plattform erm\u00f6glichen, traditionelle Batch-Systeme zu \u00fcbertreffen.<br \/><br \/>\r\nVon der Theorie zur dynamischen Steuerung:<br \/><br \/>\r\nLars promovierte an der ETH Z\u00fcrich in der Morbidelli-Gruppe, wo er eine zentrale Rolle bei der Erfindung von MCSGP (Multi-column Counter-current Solvent Gradient Purification) spielte. Seine Forschung ging \u00fcber die Hardware hinaus; er konzentrierte sich auf die Dynamik kontinuierlicher Prozesse und entwickelte die grundlegenden Algorithmen, die zu den propriet\u00e4ren dynamischen Prozesssteuerungen von YMC ChromaCon (wie AutomAb und AutoPeak) werden sollten.  <br \/><br \/>\r\nInnovation vorantreiben Bei ChromaCon schl\u00e4gt Lars die Br\u00fccke zwischen Chemieingenieurwesen und Softwareentwicklung. Er verantwortet die Weiterentwicklung der Betriebssoftware ChromIQ und stellt sicher, dass komplexe kontinuierliche Prozesse in GMP-Umgebungen einfach betrieben werden k\u00f6nnen. Seine Arbeit ist entscheidend f\u00fcr Kunden, die digitale Zwillinge und fortschrittliche Prozessmodellierung in ihren Aufreinigungs-Workflows implementieren m\u00f6chten.<br \/><br \/>\r\nKernkompetenzen:<br \/><br \/>\r\nDynamische Prozessregelung (PAT) &amp; Automatisierung<br \/><br \/>\r\nChromatographische Prozessmodellierung &amp; Simulation<br \/><br \/>\r\nKontinuierliches Prozessdesign (Twin-Column-Technologie)  <\/p>\n                                <\/div>\n                            \n                            <div class=\"flex gap-3 flex-shrink-0\">\n                                                                    <a\n                                        href=\"https:\/\/www.linkedin.com\/in\/lars-aumann-7a19b149\/\"\n                                        target=\"_blank\"\n                                        rel=\"noopener noreferrer\"\n                                        class=\"w-[50px] h-[50px] md:w-[61px] md:h-[61px] rounded-full bg-transparent border border-white\/20 box-border text-white flex items-center justify-center transition-colors flex-shrink-0 cursor-pointer\"\n                                        aria-label=\"LinkedIn-Profil f\u00fcr Dr. Lars Aumann\">\n                                        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 448 512\" class=\"svg-inline--fa w-[50px] h-[50px] md:w-[61px] md:h-[61px]\" role=\"img\" aria-hidden=\"true\" style=\"color:currentColor\"><!--! Font Awesome Free 6.7.2 by @fontawesome - https:\/\/fontawesome.com License - https:\/\/fontawesome.com\/license\/free (Icons: CC BY 4.0, Fonts: SIL OFL 1.1, Code: MIT License) Copyright 2024 Fonticons, Inc. --><path d=\"M416 32H31.9C14.3 32 0 46.5 0 64.3v383.4C0 465.5 14.3 480 31.9 480H416c17.6 0 32-14.5 32-32.3V64.3c0-17.8-14.4-32.3-32-32.3zM135.4 416H69V202.2h66.5V416zm-33.2-243c-21.3 0-38.5-17.3-38.5-38.5S80.9 96 102.2 96c21.2 0 38.5 17.3 38.5 38.5 0 21.3-17.2 38.5-38.5 38.5zm282.1 243h-66.4V312c0-24.8-.5-56.7-34.5-56.7-34.6 0-39.9 27-39.9 54.9V416h-66.4V202.2h63.7v29.2h.9c8.9-16.8 30.6-34.5 62.9-34.5 67.2 0 79.7 44.3 79.7 101.9V416z\" fill=\"currentColor\"><\/path><\/svg>\n                                    <\/a>\n                                \n                                                                    <span data-email=\"info@chromacon.com\">\n                                        <a\n                                            href=\"mailto:info@chromacon.com\"\n                                            class=\"w-[50px] h-[50px] md:w-[61px] md:h-[61px] rounded-full bg-transparent border border-white\/20 box-border text-white flex items-center justify-center transition-colors flex-shrink-0 cursor-pointer\"\n                                            aria-label=\"E-Mail Dr. Lars Aumann\">\n                                            <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa w-[50px] h-[50px] md:w-[61px] md:h-[61px]\" role=\"img\" aria-hidden=\"true\" style=\"color:currentColor\"><!--! Font Awesome Free 6.7.2 by @fontawesome - https:\/\/fontawesome.com License - https:\/\/fontawesome.com\/license\/free (Icons: CC BY 4.0, Fonts: SIL OFL 1.1, Code: MIT License) Copyright 2024 Fonticons, Inc. --><path d=\"M48 64C21.5 64 0 85.5 0 112c0 15.1 7.1 29.3 19.2 38.4L236.8 313.6c11.4 8.5 27 8.5 38.4 0L492.8 150.4c12.1-9.1 19.2-23.3 19.2-38.4c0-26.5-21.5-48-48-48L48 64zM0 176L0 384c0 35.3 28.7 64 64 64l384 0c35.3 0 64-28.7 64-64l0-208L294.4 339.2c-22.8 17.1-54 17.1-76.8 0L0 176z\" fill=\"currentColor\"><\/path><\/svg>\n                                        <\/a>\n                                    <\/span>\n                                                            <\/div>\n                        <\/div>\n                    <\/div>\n                <\/div>\n                            <div class=\"block-team__card relative aspect-[9\/10] overflow-hidden group\" data-member-id=\"team-member-2\">\n                                            <div class=\"block-team__card-image absolute inset-0\">\n                            <img decoding=\"async\" width=\"819\" height=\"1024\" src=\"https:\/\/www.chromacon.com\/wp-content\/uploads\/2026\/02\/CC_S_v1-819x1024.jpg\" class=\"!size-full object-cover\" alt=\"Dr. Sebastian Vogg\" srcset=\"https:\/\/www.chromacon.com\/wp-content\/uploads\/2026\/02\/CC_S_v1-819x1024.jpg 819w, https:\/\/www.chromacon.com\/wp-content\/uploads\/2026\/02\/CC_S_v1-240x300.jpg 240w, https:\/\/www.chromacon.com\/wp-content\/uploads\/2026\/02\/CC_S_v1-768x960.jpg 768w, https:\/\/www.chromacon.com\/wp-content\/uploads\/2026\/02\/CC_S_v1-1229x1536.jpg 1229w, https:\/\/www.chromacon.com\/wp-content\/uploads\/2026\/02\/CC_S_v1-1639x2048.jpg 1639w, https:\/\/www.chromacon.com\/wp-content\/uploads\/2026\/02\/CC_S_v1-scaled.jpg 2048w\" sizes=\"(max-width: 819px) 100vw, 819px\" \/>                        <\/div>\n                    \n                    <div class=\"block-team__card-collapsed absolute inset-0 bg-transparent flex flex-col justify-end transition-opacity duration-300\" data-state=\"collapsed\">\n                        <div class=\"p-6\">\n                            <div class=\"flex items-start\">\n                                <div class=\"block-team__collapsed-text text-white relative pl-5 space-y-1.5\">\n                                                                            <span class=\"text-h3 leading-h4 md:text-h4 md:leading-h4 block\">Dr. Sebastian Vogg<\/span>\n                                                                                                                <span class=\"text-s md:text-m block\">Leiter Forschung &amp; Entwicklung<\/span>\n                                                                    <\/div>\n                            <\/div>\n                            <button\n                                class=\"block-team__card-expand-btn absolute bottom-[24px] right-[24px] md:bottom-[28px] md:right-[28px] w-[50px] h-[50px] md:w-[57px] md:h-[57px] rounded-full bg-secondary-700 text-white flex items-center justify-center transition-colors box-border cursor-pointer\"\n                                aria-label=\"Dr. Sebastian Vogg-Details erweitern\"\n                                data-action=\"expand\">\n                                <span class=\"text-2xl font-light\">+<\/span>\n                            <\/button>\n                        <\/div>\n                    <\/div>\n\n                    <div class=\"block-team__card-expanded absolute inset-0 bg-secondary-700 text-white overflow-hidden flex flex-col transition-opacity duration-300 opacity-0 pointer-events-none\" data-state=\"expanded\">\n                        <button\n                            class=\"block-team__card-close-btn absolute bottom-[24px] right-[24px] md:bottom-[28px] md:right-[28px] w-[50px] h-[50px] md:w-[57px] md:h-[57px] rounded-full bg-secondary-700 border border-white box-border text-white flex items-center justify-center transition-colors z-10 cursor-pointer\"\n                            aria-label=\"Schlie\u00dfen\"\n                            data-action=\"close\">\n                            <span class=\"text-2xl font-light leading-[0] block\">\u00d7<\/span>\n                        <\/button>\n\n                        <div class=\"block-team__card-expanded-inner flex-1 flex flex-col overflow-y-auto p-fluid-m pb-[28px] gap-y-fluid-xs\">\n\n                            <div class=\"block-team__collapsed-text text-white relative pl-5 space-y-1.5 hidden md:block\">\n                                                                    <span class=\"text-h4 leading-h4 block\">Dr. Sebastian Vogg<\/span>\n                                                                                                    <span class=\"text-s md:text-m block\">Leiter Forschung &amp; Entwicklung<\/span>\n                                                            <\/div>\n\n                                                            <div class=\"flex-shrink-0\">\n                                    <p class=\"text-m text-white\">Als Leiter der F&amp;E bei YMC ChromaCon leitet Dr. Sebastian Vogg die Entwicklung von L\u00f6sungen f\u00fcr die kontinuierliche Chromatographie. Seine Arbeit konzentriert sich auf die Prozessintensivierung und die Integration digitaler Werkzeuge und Automatisierung in Fertigungsworkflows.<br \/><br \/>\r\nHintergrund <br \/><br \/>\r\nSebastian studierte Chemieingenieurwesen an der ETH Z\u00fcrich, wobei er seine Masterarbeit am MIT in der Gruppe von Gregory Stephanopoulos durchf\u00fchrte. Er promovierte an der ETH Z\u00fcrich in der Morbidelli-Gruppe mit Spezialisierung auf kontinuierliche und integrierte Biofertigung sowie Frontalchromatographie.<br \/><br \/>\r\nT\u00e4tigkeit bei YMC ChromaCon Sebastian leitet das Forschungs- und Entwicklungsteam, das an Technologien wie MCSGP und CaptureSMB sowie an automatisierten Steuerungsans\u00e4tzen f\u00fcr diese Prozesse arbeitet. Seine Arbeit deckt die gesamte Bandbreite der Entwicklung der kontinuierlichen Chromatographie ab \u2013 von der Ausr\u00fcstung und Software bis hin zu den Methoden, die eingesetzt werden, um neue Aufreinigungsprozesse in die Fertigung zu bringen. Damit unterst\u00fctzt er Kunden bei der Modernisierung, Intensivierung und Automatisierung ihres Downstream-Processings.<br \/><br \/>\r\nKernkompetenzen:<br \/><br \/>\r\nKontinuierliche und integrierte Biofertigung<br \/><br \/>\r\nKontinuierliche Chromatographie<br \/><br \/>\r\nMechanistische Modellierung &amp; Prozesssimulation   <br \/><br \/>\r\n<\/p>\n                                <\/div>\n                            \n                            <div class=\"flex gap-3 flex-shrink-0\">\n                                                                    <a\n                                        href=\"https:\/\/www.linkedin.com\/in\/sebastian-vogg\/\"\n                                        target=\"_blank\"\n                                        rel=\"noopener noreferrer\"\n                                        class=\"w-[50px] h-[50px] md:w-[61px] md:h-[61px] rounded-full bg-transparent border border-white\/20 box-border text-white flex items-center justify-center transition-colors flex-shrink-0 cursor-pointer\"\n                                        aria-label=\"LinkedIn-Profil f\u00fcr Dr. Sebastian Vogg\">\n                                        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 448 512\" class=\"svg-inline--fa w-[50px] h-[50px] md:w-[61px] md:h-[61px]\" role=\"img\" aria-hidden=\"true\" style=\"color:currentColor\"><!--! Font Awesome Free 6.7.2 by @fontawesome - https:\/\/fontawesome.com License - https:\/\/fontawesome.com\/license\/free (Icons: CC BY 4.0, Fonts: SIL OFL 1.1, Code: MIT License) Copyright 2024 Fonticons, Inc. --><path d=\"M416 32H31.9C14.3 32 0 46.5 0 64.3v383.4C0 465.5 14.3 480 31.9 480H416c17.6 0 32-14.5 32-32.3V64.3c0-17.8-14.4-32.3-32-32.3zM135.4 416H69V202.2h66.5V416zm-33.2-243c-21.3 0-38.5-17.3-38.5-38.5S80.9 96 102.2 96c21.2 0 38.5 17.3 38.5 38.5 0 21.3-17.2 38.5-38.5 38.5zm282.1 243h-66.4V312c0-24.8-.5-56.7-34.5-56.7-34.6 0-39.9 27-39.9 54.9V416h-66.4V202.2h63.7v29.2h.9c8.9-16.8 30.6-34.5 62.9-34.5 67.2 0 79.7 44.3 79.7 101.9V416z\" fill=\"currentColor\"><\/path><\/svg>\n                                    <\/a>\n                                \n                                                                    <span data-email=\"info@chromacon.com\">\n                                        <a\n                                            href=\"mailto:info@chromacon.com\"\n                                            class=\"w-[50px] h-[50px] md:w-[61px] md:h-[61px] rounded-full bg-transparent border border-white\/20 box-border text-white flex items-center justify-center transition-colors flex-shrink-0 cursor-pointer\"\n                                            aria-label=\"E-Mail Dr. Sebastian Vogg\">\n                                            <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa w-[50px] h-[50px] md:w-[61px] md:h-[61px]\" role=\"img\" aria-hidden=\"true\" style=\"color:currentColor\"><!--! Font Awesome Free 6.7.2 by @fontawesome - https:\/\/fontawesome.com License - https:\/\/fontawesome.com\/license\/free (Icons: CC BY 4.0, Fonts: SIL OFL 1.1, Code: MIT License) Copyright 2024 Fonticons, Inc. --><path d=\"M48 64C21.5 64 0 85.5 0 112c0 15.1 7.1 29.3 19.2 38.4L236.8 313.6c11.4 8.5 27 8.5 38.4 0L492.8 150.4c12.1-9.1 19.2-23.3 19.2-38.4c0-26.5-21.5-48-48-48L48 64zM0 176L0 384c0 35.3 28.7 64 64 64l384 0c35.3 0 64-28.7 64-64l0-208L294.4 339.2c-22.8 17.1-54 17.1-76.8 0L0 176z\" fill=\"currentColor\"><\/path><\/svg>\n                                        <\/a>\n                                    <\/span>\n                                                            <\/div>\n                        <\/div>\n                    <\/div>\n                <\/div>\n                            <div class=\"block-team__card relative aspect-[9\/10] overflow-hidden group\" data-member-id=\"team-member-3\">\n                                            <div class=\"block-team__card-image absolute inset-0\">\n                            <img decoding=\"async\" width=\"840\" height=\"1024\" src=\"https:\/\/www.chromacon.com\/wp-content\/uploads\/2026\/03\/CC_J_v1-scaled-e1772720161614-840x1024.jpg\" class=\"!size-full object-cover\" alt=\"Jennifer Kamer\" srcset=\"https:\/\/www.chromacon.com\/wp-content\/uploads\/2026\/03\/CC_J_v1-scaled-e1772720161614-840x1024.jpg 840w, https:\/\/www.chromacon.com\/wp-content\/uploads\/2026\/03\/CC_J_v1-scaled-e1772720161614-246x300.jpg 246w, https:\/\/www.chromacon.com\/wp-content\/uploads\/2026\/03\/CC_J_v1-scaled-e1772720161614-768x936.jpg 768w, https:\/\/www.chromacon.com\/wp-content\/uploads\/2026\/03\/CC_J_v1-scaled-e1772720161614-1260x1536.jpg 1260w, https:\/\/www.chromacon.com\/wp-content\/uploads\/2026\/03\/CC_J_v1-scaled-e1772720161614-1681x2048.jpg 1681w, https:\/\/www.chromacon.com\/wp-content\/uploads\/2026\/03\/CC_J_v1-scaled-e1772720161614.jpg 1852w\" sizes=\"(max-width: 840px) 100vw, 840px\" \/>                        <\/div>\n                    \n                    <div class=\"block-team__card-collapsed absolute inset-0 bg-transparent flex flex-col justify-end transition-opacity duration-300\" data-state=\"collapsed\">\n                        <div class=\"p-6\">\n                            <div class=\"flex items-start\">\n                                <div class=\"block-team__collapsed-text text-white relative pl-5 space-y-1.5\">\n                                                                            <span class=\"text-h3 leading-h4 md:text-h4 md:leading-h4 block\">Jennifer Kamer<\/span>\n                                                                                                                <span class=\"text-s md:text-m block\">Leiterin Administration<\/span>\n                                                                    <\/div>\n                            <\/div>\n                            <button\n                                class=\"block-team__card-expand-btn absolute bottom-[24px] right-[24px] md:bottom-[28px] md:right-[28px] w-[50px] h-[50px] md:w-[57px] md:h-[57px] rounded-full bg-secondary-700 text-white flex items-center justify-center transition-colors box-border cursor-pointer\"\n                                aria-label=\"Jennifer Kamer-Details erweitern\"\n                                data-action=\"expand\">\n                                <span class=\"text-2xl font-light\">+<\/span>\n                            <\/button>\n                        <\/div>\n                    <\/div>\n\n                    <div class=\"block-team__card-expanded absolute inset-0 bg-secondary-700 text-white overflow-hidden flex flex-col transition-opacity duration-300 opacity-0 pointer-events-none\" data-state=\"expanded\">\n                        <button\n                            class=\"block-team__card-close-btn absolute bottom-[24px] right-[24px] md:bottom-[28px] md:right-[28px] w-[50px] h-[50px] md:w-[57px] md:h-[57px] rounded-full bg-secondary-700 border border-white box-border text-white flex items-center justify-center transition-colors z-10 cursor-pointer\"\n                            aria-label=\"Schlie\u00dfen\"\n                            data-action=\"close\">\n                            <span class=\"text-2xl font-light leading-[0] block\">\u00d7<\/span>\n                        <\/button>\n\n                        <div class=\"block-team__card-expanded-inner flex-1 flex flex-col overflow-y-auto p-fluid-m pb-[28px] gap-y-fluid-xs\">\n\n                            <div class=\"block-team__collapsed-text text-white relative pl-5 space-y-1.5 hidden md:block\">\n                                                                    <span class=\"text-h4 leading-h4 block\">Jennifer Kamer<\/span>\n                                                                                                    <span class=\"text-s md:text-m block\">Leiterin Administration<\/span>\n                                                            <\/div>\n\n                                                            <div class=\"flex-shrink-0\">\n                                    <p class=\"text-m text-white\">Jennifer Kamer sorgt daf\u00fcr, dass YMC ChromaCon mit der gleichen Pr\u00e4zision l\u00e4uft, die das Unternehmen von seiner Wissenschaft verlangt. Als Leiterin der Administration ist sie das operative R\u00fcckgrat der Organisation \u2013 sie \u00fcberwacht Finanzen, Lieferkette, Auftragsabwicklung und Personalwesen mit ruhiger Effizienz und fundierter Expertise.<br \/><br \/>\r\nEine branchen\u00fcbergreifende Karriere:<br \/><br \/>\r\nJennifers beruflicher Weg begann mit einer kaufm\u00e4nnischen Lehre \u2013 inklusive Berufsmaturit\u00e4t \u2013 in einem Notariat im Kanton Z\u00fcrich, was ihr die finanzielle und rechtliche Disziplin vermittelte, die ihre Karriere gepr\u00e4gt hat. Sp\u00e4ter leitete sie die Print- und Au\u00dfenwerbung bei einer gro\u00dfen Medienagentur, bevor sie als Leiterin Administration und stellvertretende CEO der Simba-Dickie (Switzerland) AG, der Schweizer Tochtergesellschaft der internationalen Simba-Gruppe, in die Gesch\u00e4ftsleitung aufstieg. Sp\u00e4ter leitete sie die Schweizer Niederlassung von Keyser &amp; Mackay, einem Rohstoffdistributor, und vervollst\u00e4ndigte damit ihre Expertise in den Bereichen Lieferkette und Gesch\u00e4ftsbetrieb.<br \/><br \/>\r\nDer Motor hinter der Organisation:<br \/><br \/>\r\nBei YMC ChromaCon tr\u00e4gt Jennifer die alleinige Verantwortung f\u00fcr die Buchhaltung, Debitoren- und Kreditorenmanagement, Finanzberichterstattung, den Einkauf sowie das Auftragsmanagement von der Vorbereitung bis zur Fakturierung. Zudem tr\u00e4gt sie die administrative Verantwortung f\u00fcr das Personalwesen und \u00fcberwacht die On- und Offboarding-Prozesse. Ihr branchen\u00fcbergreifender Hintergrund \u2013 von Recht \u00fcber Medien und Konsumg\u00fcter bis hin zum Vertrieb \u2013 verleiht ihr eine einzigartig breite Perspektive und stellt sicher, dass die kommerziellen und operativen Prozesse von YMC ChromaCon immer einen Schritt voraus sind.     <\/p>\n                                <\/div>\n                            \n                            <div class=\"flex gap-3 flex-shrink-0\">\n                                                                    <a\n                                        href=\"https:\/\/www.linkedin.com\/in\/jennifer-kamer-1b149014b\/\"\n                                        target=\"_blank\"\n                                        rel=\"noopener noreferrer\"\n                                        class=\"w-[50px] h-[50px] md:w-[61px] md:h-[61px] rounded-full bg-transparent border border-white\/20 box-border text-white flex items-center justify-center transition-colors flex-shrink-0 cursor-pointer\"\n                                        aria-label=\"LinkedIn-Profil f\u00fcr Jennifer Kamer\">\n                                        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 448 512\" class=\"svg-inline--fa w-[50px] h-[50px] md:w-[61px] md:h-[61px]\" role=\"img\" aria-hidden=\"true\" style=\"color:currentColor\"><!--! Font Awesome Free 6.7.2 by @fontawesome - https:\/\/fontawesome.com License - https:\/\/fontawesome.com\/license\/free (Icons: CC BY 4.0, Fonts: SIL OFL 1.1, Code: MIT License) Copyright 2024 Fonticons, Inc. --><path d=\"M416 32H31.9C14.3 32 0 46.5 0 64.3v383.4C0 465.5 14.3 480 31.9 480H416c17.6 0 32-14.5 32-32.3V64.3c0-17.8-14.4-32.3-32-32.3zM135.4 416H69V202.2h66.5V416zm-33.2-243c-21.3 0-38.5-17.3-38.5-38.5S80.9 96 102.2 96c21.2 0 38.5 17.3 38.5 38.5 0 21.3-17.2 38.5-38.5 38.5zm282.1 243h-66.4V312c0-24.8-.5-56.7-34.5-56.7-34.6 0-39.9 27-39.9 54.9V416h-66.4V202.2h63.7v29.2h.9c8.9-16.8 30.6-34.5 62.9-34.5 67.2 0 79.7 44.3 79.7 101.9V416z\" fill=\"currentColor\"><\/path><\/svg>\n                                    <\/a>\n                                \n                                                                    <span data-email=\"info@chromacon.com\">\n                                        <a\n                                            href=\"mailto:info@chromacon.com\"\n                                            class=\"w-[50px] h-[50px] md:w-[61px] md:h-[61px] rounded-full bg-transparent border border-white\/20 box-border text-white flex items-center justify-center transition-colors flex-shrink-0 cursor-pointer\"\n                                            aria-label=\"E-Mail Jennifer Kamer\">\n                                            <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa w-[50px] h-[50px] md:w-[61px] md:h-[61px]\" role=\"img\" aria-hidden=\"true\" style=\"color:currentColor\"><!--! Font Awesome Free 6.7.2 by @fontawesome - https:\/\/fontawesome.com License - https:\/\/fontawesome.com\/license\/free (Icons: CC BY 4.0, Fonts: SIL OFL 1.1, Code: MIT License) Copyright 2024 Fonticons, Inc. --><path d=\"M48 64C21.5 64 0 85.5 0 112c0 15.1 7.1 29.3 19.2 38.4L236.8 313.6c11.4 8.5 27 8.5 38.4 0L492.8 150.4c12.1-9.1 19.2-23.3 19.2-38.4c0-26.5-21.5-48-48-48L48 64zM0 176L0 384c0 35.3 28.7 64 64 64l384 0c35.3 0 64-28.7 64-64l0-208L294.4 339.2c-22.8 17.1-54 17.1-76.8 0L0 176z\" fill=\"currentColor\"><\/path><\/svg>\n                                        <\/a>\n                                    <\/span>\n                                                            <\/div>\n                        <\/div>\n                    <\/div>\n                <\/div>\n                            <div class=\"block-team__card relative aspect-[9\/10] overflow-hidden group\" data-member-id=\"team-member-4\">\n                                            <div class=\"block-team__card-image absolute inset-0\">\n                            <img decoding=\"async\" width=\"819\" height=\"1024\" src=\"https:\/\/www.chromacon.com\/wp-content\/uploads\/2026\/02\/CC_TH_v1-819x1024.jpg\" class=\"!size-full object-cover\" alt=\"Dr. Thomas Hug\" srcset=\"https:\/\/www.chromacon.com\/wp-content\/uploads\/2026\/02\/CC_TH_v1-819x1024.jpg 819w, https:\/\/www.chromacon.com\/wp-content\/uploads\/2026\/02\/CC_TH_v1-240x300.jpg 240w, https:\/\/www.chromacon.com\/wp-content\/uploads\/2026\/02\/CC_TH_v1-768x960.jpg 768w, https:\/\/www.chromacon.com\/wp-content\/uploads\/2026\/02\/CC_TH_v1-1229x1536.jpg 1229w, https:\/\/www.chromacon.com\/wp-content\/uploads\/2026\/02\/CC_TH_v1-1639x2048.jpg 1639w, https:\/\/www.chromacon.com\/wp-content\/uploads\/2026\/02\/CC_TH_v1-scaled.jpg 2048w\" sizes=\"(max-width: 819px) 100vw, 819px\" \/>                        <\/div>\n                    \n                    <div class=\"block-team__card-collapsed absolute inset-0 bg-transparent flex flex-col justify-end transition-opacity duration-300\" data-state=\"collapsed\">\n                        <div class=\"p-6\">\n                            <div class=\"flex items-start\">\n                                <div class=\"block-team__collapsed-text text-white relative pl-5 space-y-1.5\">\n                                                                            <span class=\"text-h3 leading-h4 md:text-h4 md:leading-h4 block\">Dr. Thomas Hug<\/span>\n                                                                                                                <span class=\"text-s md:text-m block\">Leiter Qualit\u00e4t<\/span>\n                                                                    <\/div>\n                            <\/div>\n                            <button\n                                class=\"block-team__card-expand-btn absolute bottom-[24px] right-[24px] md:bottom-[28px] md:right-[28px] w-[50px] h-[50px] md:w-[57px] md:h-[57px] rounded-full bg-secondary-700 text-white flex items-center justify-center transition-colors box-border cursor-pointer\"\n                                aria-label=\"Dr. Thomas Hug-Details erweitern\"\n                                data-action=\"expand\">\n                                <span class=\"text-2xl font-light\">+<\/span>\n                            <\/button>\n                        <\/div>\n                    <\/div>\n\n                    <div class=\"block-team__card-expanded absolute inset-0 bg-secondary-700 text-white overflow-hidden flex flex-col transition-opacity duration-300 opacity-0 pointer-events-none\" data-state=\"expanded\">\n                        <button\n                            class=\"block-team__card-close-btn absolute bottom-[24px] right-[24px] md:bottom-[28px] md:right-[28px] w-[50px] h-[50px] md:w-[57px] md:h-[57px] rounded-full bg-secondary-700 border border-white box-border text-white flex items-center justify-center transition-colors z-10 cursor-pointer\"\n                            aria-label=\"Schlie\u00dfen\"\n                            data-action=\"close\">\n                            <span class=\"text-2xl font-light leading-[0] block\">\u00d7<\/span>\n                        <\/button>\n\n                        <div class=\"block-team__card-expanded-inner flex-1 flex flex-col overflow-y-auto p-fluid-m pb-[28px] gap-y-fluid-xs\">\n\n                            <div class=\"block-team__collapsed-text text-white relative pl-5 space-y-1.5 hidden md:block\">\n                                                                    <span class=\"text-h4 leading-h4 block\">Dr. Thomas Hug<\/span>\n                                                                                                    <span class=\"text-s md:text-m block\">Leiter Qualit\u00e4t<\/span>\n                                                            <\/div>\n\n                                                            <div class=\"flex-shrink-0\">\n                                    <p class=\"text-m text-white\">Als Leiter Qualit\u00e4t bei YMC ChromaCon fungiert Dr. Thomas Hug als W\u00e4chter unserer operativen Exzellenz. In einer Branche, in der Reinheit und Reproduzierbarkeit an erster Stelle stehen, stellt Thomas sicher, dass jedes Contichrom\u00ae-System und jedes Verbrauchsmaterial die strengen Standards erf\u00fcllt, die von unseren biopharmazeutischen Partnern gefordert werden.<br \/><br \/>\r\nDie Br\u00fccke zwischen Innovation und Compliance:<br \/><br \/>\r\nThomas \u00fcberwacht das nach ISO 9001:2015 zertifizierte Qualit\u00e4tsmanagementsystem (QMS) von YMC ChromaCon. Er spielt eine entscheidende Rolle bei der \u00dcberbr\u00fcckung der L\u00fccke zwischen unserer schnellen F&amp;E-Innovation und den regulierten Realit\u00e4ten der GMP-Fertigungsumgebung. Seine F\u00fchrung stellt sicher, dass unsere internen Prozesse \u2013 von der Qualifizierung der Lieferkette bis zur abschlie\u00dfenden Ger\u00e4tepr\u00fcfung \u2013 robust, r\u00fcckverfolgbar und skalierbar sind.<br \/><br \/>\r\nEngagement f\u00fcr den Kunden:<br \/><br \/>\r\n\u00dcber interne Audits hinaus ist Thomas der prim\u00e4re F\u00fcrsprecher f\u00fcr die Qualit\u00e4tssicherung beim Kunden. Er leitet unsere Initiativen zur kontinuierlichen Verbesserung und stellt sicher, dass Feedback aus der Praxis systematisch in unsere Fertigungsprotokolle integriert wird. Seine Arbeit garantiert, dass Kunden mit der Installation eines YMC ChromaCon-Systems in Schweizer Qualit\u00e4t investieren, der sie vertrauen k\u00f6nnen.<br \/><br \/>\r\nHauptverantwortlichkeiten:<br \/><br \/>\r\n\u00dcberwachung des Qualit\u00e4tsmanagementsystems nach ISO 9001:2015<br \/><br \/>\r\nLieferantenqualifizierung &amp; Integrit\u00e4t der Lieferkette<br \/><br \/>\r\nGMP-Compliance-Strategie &amp; interne Audits     <\/p>\n                                <\/div>\n                            \n                            <div class=\"flex gap-3 flex-shrink-0\">\n                                                                    <a\n                                        href=\"https:\/\/www.linkedin.com\/in\/thomas-hug-9b84271b\/\"\n                                        target=\"_blank\"\n                                        rel=\"noopener noreferrer\"\n                                        class=\"w-[50px] h-[50px] md:w-[61px] md:h-[61px] rounded-full bg-transparent border border-white\/20 box-border text-white flex items-center justify-center transition-colors flex-shrink-0 cursor-pointer\"\n                                        aria-label=\"LinkedIn-Profil f\u00fcr Dr. Thomas Hug\">\n                                        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 448 512\" class=\"svg-inline--fa w-[50px] h-[50px] md:w-[61px] md:h-[61px]\" role=\"img\" aria-hidden=\"true\" style=\"color:currentColor\"><!--! Font Awesome Free 6.7.2 by @fontawesome - https:\/\/fontawesome.com License - https:\/\/fontawesome.com\/license\/free (Icons: CC BY 4.0, Fonts: SIL OFL 1.1, Code: MIT License) Copyright 2024 Fonticons, Inc. --><path d=\"M416 32H31.9C14.3 32 0 46.5 0 64.3v383.4C0 465.5 14.3 480 31.9 480H416c17.6 0 32-14.5 32-32.3V64.3c0-17.8-14.4-32.3-32-32.3zM135.4 416H69V202.2h66.5V416zm-33.2-243c-21.3 0-38.5-17.3-38.5-38.5S80.9 96 102.2 96c21.2 0 38.5 17.3 38.5 38.5 0 21.3-17.2 38.5-38.5 38.5zm282.1 243h-66.4V312c0-24.8-.5-56.7-34.5-56.7-34.6 0-39.9 27-39.9 54.9V416h-66.4V202.2h63.7v29.2h.9c8.9-16.8 30.6-34.5 62.9-34.5 67.2 0 79.7 44.3 79.7 101.9V416z\" fill=\"currentColor\"><\/path><\/svg>\n                                    <\/a>\n                                \n                                                                    <span data-email=\"info@chromacon.com\">\n                                        <a\n                                            href=\"mailto:info@chromacon.com\"\n                                            class=\"w-[50px] h-[50px] md:w-[61px] md:h-[61px] rounded-full bg-transparent border border-white\/20 box-border text-white flex items-center justify-center transition-colors flex-shrink-0 cursor-pointer\"\n                                            aria-label=\"E-Mail Dr. Thomas Hug\">\n                                            <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa w-[50px] h-[50px] md:w-[61px] md:h-[61px]\" role=\"img\" aria-hidden=\"true\" style=\"color:currentColor\"><!--! Font Awesome Free 6.7.2 by @fontawesome - https:\/\/fontawesome.com License - https:\/\/fontawesome.com\/license\/free (Icons: CC BY 4.0, Fonts: SIL OFL 1.1, Code: MIT License) Copyright 2024 Fonticons, Inc. --><path d=\"M48 64C21.5 64 0 85.5 0 112c0 15.1 7.1 29.3 19.2 38.4L236.8 313.6c11.4 8.5 27 8.5 38.4 0L492.8 150.4c12.1-9.1 19.2-23.3 19.2-38.4c0-26.5-21.5-48-48-48L48 64zM0 176L0 384c0 35.3 28.7 64 64 64l384 0c35.3 0 64-28.7 64-64l0-208L294.4 339.2c-22.8 17.1-54 17.1-76.8 0L0 176z\" fill=\"currentColor\"><\/path><\/svg>\n                                        <\/a>\n                                    <\/span>\n                                                            <\/div>\n                        <\/div>\n                    <\/div>\n                <\/div>\n                            <div class=\"block-team__card relative aspect-[9\/10] overflow-hidden group\" data-member-id=\"team-member-5\">\n                                            <div class=\"block-team__card-image absolute inset-0\">\n                            <img decoding=\"async\" width=\"819\" height=\"1024\" src=\"https:\/\/www.chromacon.com\/wp-content\/uploads\/2026\/02\/CC_G_v1-819x1024.jpg\" class=\"!size-full object-cover\" alt=\"Dr. Giulio Lievore\" srcset=\"https:\/\/www.chromacon.com\/wp-content\/uploads\/2026\/02\/CC_G_v1-819x1024.jpg 819w, https:\/\/www.chromacon.com\/wp-content\/uploads\/2026\/02\/CC_G_v1-240x300.jpg 240w, https:\/\/www.chromacon.com\/wp-content\/uploads\/2026\/02\/CC_G_v1-768x960.jpg 768w, https:\/\/www.chromacon.com\/wp-content\/uploads\/2026\/02\/CC_G_v1-1229x1536.jpg 1229w, https:\/\/www.chromacon.com\/wp-content\/uploads\/2026\/02\/CC_G_v1-1638x2048.jpg 1638w, https:\/\/www.chromacon.com\/wp-content\/uploads\/2026\/02\/CC_G_v1-scaled.jpg 2048w\" sizes=\"(max-width: 819px) 100vw, 819px\" \/>                        <\/div>\n                    \n                    <div class=\"block-team__card-collapsed absolute inset-0 bg-transparent flex flex-col justify-end transition-opacity duration-300\" data-state=\"collapsed\">\n                        <div class=\"p-6\">\n                            <div class=\"flex items-start\">\n                                <div class=\"block-team__collapsed-text text-white relative pl-5 space-y-1.5\">\n                                                                            <span class=\"text-h3 leading-h4 md:text-h4 md:leading-h4 block\">Dr. Giulio Lievore<\/span>\n                                                                                                                <span class=\"text-s md:text-m block\">Key Account Manager<\/span>\n                                                                    <\/div>\n                            <\/div>\n                            <button\n                                class=\"block-team__card-expand-btn absolute bottom-[24px] right-[24px] md:bottom-[28px] md:right-[28px] w-[50px] h-[50px] md:w-[57px] md:h-[57px] rounded-full bg-secondary-700 text-white flex items-center justify-center transition-colors box-border cursor-pointer\"\n                                aria-label=\"Dr. Giulio Lievore-Details erweitern\"\n                                data-action=\"expand\">\n                                <span class=\"text-2xl font-light\">+<\/span>\n                            <\/button>\n                        <\/div>\n                    <\/div>\n\n                    <div class=\"block-team__card-expanded absolute inset-0 bg-secondary-700 text-white overflow-hidden flex flex-col transition-opacity duration-300 opacity-0 pointer-events-none\" data-state=\"expanded\">\n                        <button\n                            class=\"block-team__card-close-btn absolute bottom-[24px] right-[24px] md:bottom-[28px] md:right-[28px] w-[50px] h-[50px] md:w-[57px] md:h-[57px] rounded-full bg-secondary-700 border border-white box-border text-white flex items-center justify-center transition-colors z-10 cursor-pointer\"\n                            aria-label=\"Schlie\u00dfen\"\n                            data-action=\"close\">\n                            <span class=\"text-2xl font-light leading-[0] block\">\u00d7<\/span>\n                        <\/button>\n\n                        <div class=\"block-team__card-expanded-inner flex-1 flex flex-col overflow-y-auto p-fluid-m pb-[28px] gap-y-fluid-xs\">\n\n                            <div class=\"block-team__collapsed-text text-white relative pl-5 space-y-1.5 hidden md:block\">\n                                                                    <span class=\"text-h4 leading-h4 block\">Dr. Giulio Lievore<\/span>\n                                                                                                    <span class=\"text-s md:text-m block\">Key Account Manager<\/span>\n                                                            <\/div>\n\n                                                            <div class=\"flex-shrink-0\">\n                                    <p class=\"text-m text-white\">Dr. Giulio Lievore bringt eine einzigartige \u201eScientist-First\u201c-Herangehensweise in seine Rolle als Account Manager f\u00fcr Europa ein. Im Gegensatz zu traditionellen Vertriebsmitarbeitern hat Giulio einen Doktortitel in Chemie, wobei sich seine Forschung speziell auf den \u00dcbergang von der Batch- zur kontinuierlichen Chromatographie f\u00fcr therapeutische Peptide konzentrierte.<br \/><br \/>\r\nEin tiefgreifender technischer Partner:<br \/><br \/>\r\nBevor er dem kommerziellen Team beitrat, war Giulio aktiver Forscher im Bereich der Aufreinigung. Er hat zahlreiche von Fachkollegen begutachtete Publikationen zu MCSGP- und N-Rich-Technologien mitverfasst und dabei eng mit den Erfindern der Contichrom\u00ae-Plattform zusammengearbeitet. Diese tiefe technische DNA erm\u00f6glicht es ihm, als Berater f\u00fcr unsere Partner zu fungieren und ihnen nicht nur beim Kauf eines Systems, sondern auch bei der Entwicklung eines effizienteren Prozesses zu helfen.<br \/><br \/>\r\nL\u00f6sung realer Herausforderungen:<br \/><br \/>\r\nGiulio ist darauf spezialisiert, europ\u00e4ischen Biopharma-Unternehmen bei der Skalierung ihrer Aufreinigung von Oligonukleotiden, Peptiden und Biologika zu helfen. Er arbeitet eng mit Prozessingenieuren zusammen, um deren aktuelle Engp\u00e4sse zu analysieren und zu modellieren, wie die Twin-Column-Technologie von YMC ChromaCon ihren Ertrag und ihre Reinheit verbessern kann.<br \/><br \/>\r\nKernkompetenzen:<br \/><br \/>\r\nAufreinigungsstrategien f\u00fcr Peptide, Oligonukleotide &amp; Biologika<br \/><br \/>\r\nN-Rich-Prozess zur Verunreinigungsisolierung<br \/><br \/>\r\nProzess\u00f6konomie &amp; Scale-up-Analyse<\/p>\n                                <\/div>\n                            \n                            <div class=\"flex gap-3 flex-shrink-0\">\n                                                                    <a\n                                        href=\"https:\/\/www.linkedin.com\/in\/giuliolievore\/\"\n                                        target=\"_blank\"\n                                        rel=\"noopener noreferrer\"\n                                        class=\"w-[50px] h-[50px] md:w-[61px] md:h-[61px] rounded-full bg-transparent border border-white\/20 box-border text-white flex items-center justify-center transition-colors flex-shrink-0 cursor-pointer\"\n                                        aria-label=\"LinkedIn-Profil f\u00fcr Dr. Giulio Lievore\">\n                                        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 448 512\" class=\"svg-inline--fa w-[50px] h-[50px] md:w-[61px] md:h-[61px]\" role=\"img\" aria-hidden=\"true\" style=\"color:currentColor\"><!--! Font Awesome Free 6.7.2 by @fontawesome - https:\/\/fontawesome.com License - https:\/\/fontawesome.com\/license\/free (Icons: CC BY 4.0, Fonts: SIL OFL 1.1, Code: MIT License) Copyright 2024 Fonticons, Inc. --><path d=\"M416 32H31.9C14.3 32 0 46.5 0 64.3v383.4C0 465.5 14.3 480 31.9 480H416c17.6 0 32-14.5 32-32.3V64.3c0-17.8-14.4-32.3-32-32.3zM135.4 416H69V202.2h66.5V416zm-33.2-243c-21.3 0-38.5-17.3-38.5-38.5S80.9 96 102.2 96c21.2 0 38.5 17.3 38.5 38.5 0 21.3-17.2 38.5-38.5 38.5zm282.1 243h-66.4V312c0-24.8-.5-56.7-34.5-56.7-34.6 0-39.9 27-39.9 54.9V416h-66.4V202.2h63.7v29.2h.9c8.9-16.8 30.6-34.5 62.9-34.5 67.2 0 79.7 44.3 79.7 101.9V416z\" fill=\"currentColor\"><\/path><\/svg>\n                                    <\/a>\n                                \n                                                                    <span data-email=\"info@chromacon.com\">\n                                        <a\n                                            href=\"mailto:info@chromacon.com\"\n                                            class=\"w-[50px] h-[50px] md:w-[61px] md:h-[61px] rounded-full bg-transparent border border-white\/20 box-border text-white flex items-center justify-center transition-colors flex-shrink-0 cursor-pointer\"\n                                            aria-label=\"E-Mail Dr. Giulio Lievore\">\n                                            <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa w-[50px] h-[50px] md:w-[61px] md:h-[61px]\" role=\"img\" aria-hidden=\"true\" style=\"color:currentColor\"><!--! Font Awesome Free 6.7.2 by @fontawesome - https:\/\/fontawesome.com License - https:\/\/fontawesome.com\/license\/free (Icons: CC BY 4.0, Fonts: SIL OFL 1.1, Code: MIT License) Copyright 2024 Fonticons, Inc. --><path d=\"M48 64C21.5 64 0 85.5 0 112c0 15.1 7.1 29.3 19.2 38.4L236.8 313.6c11.4 8.5 27 8.5 38.4 0L492.8 150.4c12.1-9.1 19.2-23.3 19.2-38.4c0-26.5-21.5-48-48-48L48 64zM0 176L0 384c0 35.3 28.7 64 64 64l384 0c35.3 0 64-28.7 64-64l0-208L294.4 339.2c-22.8 17.1-54 17.1-76.8 0L0 176z\" fill=\"currentColor\"><\/path><\/svg>\n                                        <\/a>\n                                    <\/span>\n                                                            <\/div>\n                        <\/div>\n                    <\/div>\n                <\/div>\n                    <\/div>\n    \n<\/div><\/section><section id=\"block_be1bc4189e79e6518e1f294f3e26dd05\" class=\"block-featured-news pt-fluid-4xl-plus pb-fluid-4xl alignfull  \"><div class=\"l-wrap\">\n    <div class=\"featured-news-wrapper\" data-post-type=\"post\">\n                <div class=\"flex flex-col md:flex-row justify-between mb-fluid-3xl gap-fluid-xl\">\n                            <div class=\"featured-news-header md:w-1\/2\">\n                    <h2 class=\"text-display-m leading-display-m md:text-h1 md:leading-h1 typo-off text-primary-800\">\n                        News &amp; Event                    <\/h2>\n                <\/div>\n                        <nav class=\"featured-news-categories md:w-1\/2\" role=\"navigation\" aria-label=\"Category navigation\">\n                <ul class=\"flex gap-x-fluid-s-plus gap-y-fluid-4xl-plus md:justify-end overflow-x-auto whitespace-nowrap\">\n                                            <li>\n                            <a\n                                href=\"#\"\n                                class=\"block pb-4 text-gray-600 hover:text-gray-900 transition-colors relative text-18 md:text-20 text-gray-900 font-medium\"\n                                data-category-slug=\"\">\n                                Alle                                                                    <span class=\"absolute bottom-0 left-0 right-0 h-0.5 bg-primary-800\"><\/span>\n                                                            <\/a>\n                        <\/li>\n                                            <li>\n                            <a\n                                href=\"#\"\n                                class=\"block pb-4 text-gray-600 hover:text-gray-900 transition-colors relative text-18 md:text-20 \"\n                                data-category-slug=\"neuigkeiten-veranstaltungen\">\n                                Neuigkeiten &amp; Veranstaltungen                                                            <\/a>\n                        <\/li>\n                                    <\/ul>\n            <\/nav>\n        <\/div>\n\n\n                            <div class=\"featured-news-content grid grid-cols-1 lg:grid-cols-2 gap-fluid-xl mb-fluid-2xl\">\n                                                    <div class=\"featured-news-left md:pr-fluid-xl md:border-r border-primary-800\/30\">\n                        <article class=\"news-card overflow-hidden\">\n            \n                            <a href=\"https:\/\/www.chromacon.com\/de\/news\/2026-workshop-zur-kontinuierlichen-chromatographie-fuer-mabs-oligonukleotide-und-peptide\/\" class=\"block relative w-full aspect-[4\/3] overflow-hidden mb-fluid-s-plus\">\n                <img decoding=\"async\"\n                    src=\"https:\/\/www.chromacon.com\/wp-content\/uploads\/2025\/11\/FNHW-Picture1-1-e1774363821373-768x599.png\"\n                    alt=\"2026 \u2013 Workshop zur kontinuierlichen Chromatographie f\u00fcr mAbs, Oligonukleotide und Peptide\"\n                    class=\"w-full h-full object-cover !m-0\"\n                    loading=\"lazy\" \/>\n            <\/a>\n        \n                <div class=\"flex gap-3 items-center mb-fluid-xs\">\n                            <span class=\"px-fluid-3xs py-2.5 bg-[#EEF5FE] text-secondary-700 text-s rounded-full\">\n                    Neuigkeiten &amp; Veranstaltungen                <\/span>\n                        <span class=\"text-secondary-700 text-s border border-gray-50 rounded-full px-fluid-3xs py-2.5\">\n                08 Sep 2026            <\/span>\n        <\/div>\n\n                <div class=\"\">\n                            <h3 class=\"heading-h4 !m-0 pb-fluid-xs typo-off\">\n                    <a href=\"https:\/\/www.chromacon.com\/de\/news\/2026-workshop-zur-kontinuierlichen-chromatographie-fuer-mabs-oligonukleotide-und-peptide\/\" class=\"!no-underline\">\n                        2026 \u2013 Workshop zur kontinuierlichen Chromatographie f\u00fcr mAbs, Oligonukleotide und Peptide                    <\/a>\n                <\/h3>\n            \n                            <p class=\"!mb-0\">\n                    Vom 8.\u201310. September 2026 veranstaltet das Institute for Pharma Technology der FHNW ein 3-t\u00e4giges Seminar am Campus Muttenz (Basel) in der Schweiz. In einer Kombination aus Vortr\u00e4gen, Fallstudien und praxisnahen Twin-Column-Trainings erwerben die Teilnehmenden praktische Kompetenzen in der kontinuierlichen Chromatographie f\u00fcr mAbs, Oligonukleotide, Peptide und virale Vektoren.                 <\/p>\n                    <\/div>\n\n    <\/article>\n                    <\/div>\n                \n                                                    <div class=\"featured-news-right flex flex-col gap-6\">\n                                                    <article class=\"news-card overflow-hidden flex flex-col md:flex-row gap-fluid-l\">\n            \n                            <a href=\"https:\/\/www.chromacon.com\/de\/news\/ymc-chromacon-kuendigt-contichrom-pilot-300x-an-ein-neuer-standard-fuer-kontinuierliche-chromatographie-im-pilotmassstab\/\" class=\"block relative flex-shrink-0 w-full md:w-[205px] overflow-hidden\">\n                <img decoding=\"async\"\n                    src=\"https:\/\/www.chromacon.com\/wp-content\/uploads\/2025\/08\/Gemini_Generated_Image_nqndcunqndcunqnd-768x600.jpg\"\n                    alt=\"YMC ChromaCon k\u00fcndigt Contichrom\u00ae PILOT 300X an \u2013 ein neuer Standard f\u00fcr kontinuierliche Chromatographie im Pilotma\u00dfstab\"\n                    class=\"w-full h-auto object-cover aspect-[4\/3] !m-0\"\n                    loading=\"lazy\" \/>\n            <\/a>\n        \n                <div class=\"flex flex-col flex-1 min-w-0\">\n                        <div class=\"flex gap-3 items-center mb-4.5\">\n                                    <span class=\"px-fluid-3xs py-2.5 bg-[#EEF5FE] text-secondary-700 text-s rounded-full\">\n                        Neuigkeiten &amp; Veranstaltungen                    <\/span>\n                                <span class=\"text-secondary-700 text-s border border-gray-50 rounded-full px-fluid-3xs py-2.5\">\n                    28 Aug. 2025                <\/span>\n            <\/div>\n\n                        <div class=\"flex-1 flex flex-col\">\n                                    <h3 class=\"heading-h4 !m-0 pb-fluid-3xs typo-off\">\n                        <a href=\"https:\/\/www.chromacon.com\/de\/news\/ymc-chromacon-kuendigt-contichrom-pilot-300x-an-ein-neuer-standard-fuer-kontinuierliche-chromatographie-im-pilotmassstab\/\" class=\"!no-underline\">\n                            YMC ChromaCon k\u00fcndigt Contichrom\u00ae PILOT 300X an \u2013 ein neuer Standard f\u00fcr kontinuierliche Chromatographie im Pilotma\u00dfstab                        <\/a>\n                    <\/h3>\n                \n                                    <p class=\"!mb-0\">\n                        ChromaCon AG stellt den Contichrom\u00ae PILOT 300X vor, ein pr\u00e4paratives HPLC-System der n\u00e4chsten Generation f\u00fcr kontinuierliche Chromatographie im Pilotma\u00dfstab in GMP-Umgebungen. Basierend auf der MCSGP-Technologie mit AutoPeak\u00ae-Regelung steigert es Ausbeute, Reinheit und Produktivit\u00e4t und reduziert gleichzeitig den L\u00f6sungsmittelverbrauch.                     <\/p>\n                            <\/div>\n        <\/div>\n\n    <\/article>\n                                                    <article class=\"news-card overflow-hidden flex flex-col md:flex-row gap-fluid-l\">\n            \n                            <a href=\"https:\/\/www.chromacon.com\/de\/news\/die-aera-der-grosstechnischen-peptid-oligo-reinigung-mit-mcsgp-hat-begonnen\/\" class=\"block relative flex-shrink-0 w-full md:w-[205px] overflow-hidden\">\n                <img decoding=\"async\"\n                    src=\"https:\/\/www.chromacon.com\/wp-content\/uploads\/2026\/04\/Gemini_Generated_Image_oizybyoizybyoizy-768x768.jpg\"\n                    alt=\"\u201eDie \u00c4ra der gro\u00dftechnischen Peptid- &amp; Oligo-Reinigung mit MCSGP hat begonnen\u201c\"\n                    class=\"w-full h-auto object-cover aspect-[4\/3] !m-0\"\n                    loading=\"lazy\" \/>\n            <\/a>\n        \n                <div class=\"flex flex-col flex-1 min-w-0\">\n                        <div class=\"flex gap-3 items-center mb-4.5\">\n                                    <span class=\"px-fluid-3xs py-2.5 bg-[#EEF5FE] text-secondary-700 text-s rounded-full\">\n                        Neuigkeiten &amp; Veranstaltungen                    <\/span>\n                                <span class=\"text-secondary-700 text-s border border-gray-50 rounded-full px-fluid-3xs py-2.5\">\n                    01 Feb. 2024                <\/span>\n            <\/div>\n\n                        <div class=\"flex-1 flex flex-col\">\n                                    <h3 class=\"heading-h4 !m-0 pb-fluid-3xs typo-off\">\n                        <a href=\"https:\/\/www.chromacon.com\/de\/news\/die-aera-der-grosstechnischen-peptid-oligo-reinigung-mit-mcsgp-hat-begonnen\/\" class=\"!no-underline\">\n                            \u201eDie \u00c4ra der gro\u00dftechnischen Peptid- &amp; Oligo-Reinigung mit MCSGP hat begonnen\u201c                        <\/a>\n                    <\/h3>\n                \n                                    <p class=\"!mb-0\">\n                        Bachem hat erfolgreich auf die gro\u00dftechnische, GMP-konforme Reinigung von Peptiden und Oligonukleotiden mittels kontinuierlicher MCSGP-Chromatographie umgestellt. Dieser Meilenstein best\u00e4tigt MCSGP als bew\u00e4hrte Produktionstechnologie f\u00fcr den globalen TIDES-Markt \u2013 mit einer Kapazit\u00e4t von bis zu zwei Tonnen Rohpeptiden pro Linie.                     <\/p>\n                            <\/div>\n        <\/div>\n\n    <\/article>\n                                                    <article class=\"news-card overflow-hidden flex flex-col md:flex-row gap-fluid-l\">\n            \n                            <a href=\"https:\/\/www.chromacon.com\/de\/news\/fda-waehlt-ymc-zweisaeulen-system-fuer-kontinuierliche-chromatographie-zur-evaluierung-aus\/\" class=\"block relative flex-shrink-0 w-full md:w-[205px] overflow-hidden\">\n                <img decoding=\"async\"\n                    src=\"https:\/\/www.chromacon.com\/wp-content\/uploads\/2020\/07\/Gemini_Generated_Image_tm5sztm5sztm5szt-768x600.jpg\"\n                    alt=\"FDA w\u00e4hlt YMC-Zweis\u00e4ulen-System f\u00fcr kontinuierliche Chromatographie zur Evaluierung aus\"\n                    class=\"w-full h-auto object-cover aspect-[4\/3] !m-0\"\n                    loading=\"lazy\" \/>\n            <\/a>\n        \n                <div class=\"flex flex-col flex-1 min-w-0\">\n                        <div class=\"flex gap-3 items-center mb-4.5\">\n                                    <span class=\"px-fluid-3xs py-2.5 bg-[#EEF5FE] text-secondary-700 text-s rounded-full\">\n                        Neuigkeiten &amp; Veranstaltungen                    <\/span>\n                                <span class=\"text-secondary-700 text-s border border-gray-50 rounded-full px-fluid-3xs py-2.5\">\n                    16 Juli 2020                <\/span>\n            <\/div>\n\n                        <div class=\"flex-1 flex flex-col\">\n                                    <h3 class=\"heading-h4 !m-0 pb-fluid-3xs typo-off\">\n                        <a href=\"https:\/\/www.chromacon.com\/de\/news\/fda-waehlt-ymc-zweisaeulen-system-fuer-kontinuierliche-chromatographie-zur-evaluierung-aus\/\" class=\"!no-underline\">\n                            FDA w\u00e4hlt YMC-Zweis\u00e4ulen-System f\u00fcr kontinuierliche Chromatographie zur Evaluierung aus                        <\/a>\n                    <\/h3>\n                \n                                    <p class=\"!mb-0\">\n                        Die US-amerikanische FDA hat das YMC Contichrom\u00ae CUBE Zweis\u00e4ulen-System f\u00fcr die kontinuierliche Chromatographie ausgew\u00e4hlt, um fortschrittliche Aufreinigungsstrategien f\u00fcr die biopharmazeutische Herstellung zu evaluieren. Diese Anschaffung signalisiert ein wachsendes regulatorisches Interesse an der kontinuierlichen Chromatographie zur Kostensenkung und Produktivit\u00e4tssteigerung.                     <\/p>\n                            <\/div>\n        <\/div>\n\n    <\/article>\n                                            <\/div>\n                            <\/div>\n\n                                        <div class=\"featured-news-button flex justify-center md:justify-end\">\n                    <span class=\"c-btn-focus-wrapper\"><a href=\"https:\/\/www.chromacon.com\/de\/neuigkeiten-veranstaltungen\/\" class=\"c-btn c-btn--regular c-btn--secondary c-btn--light w-full md:w-auto\"><span>Weitere Neuigkeiten anzeigen<\/span><\/a><\/span>                <\/div>\n                        <\/div>\n\n<\/div><\/section><section id=\"block_51ffd1ec0bc59c9717207aeb13218b64\" class=\"block-call-to-action py-fluid-6xl bg-secondary-700 alignfull  \" style=\"--block-bg-image: url(https:\/\/www.chromacon.com\/wp-content\/themes\/chromacon\/assets\/img\/layout\/block-background-poly.svg);\"><div class=\"l-wrap\">\n    <div class=\"flex flex-col gap-6 items-start text-left\">\n                    <p class=\"heading-h1 !text-white !my-0 max-w-[1015px]\">\n                YMC ChromaCon Chromatographie-Newsletter.<br \/>\r\nEtwa eine E-Mail pro Monat. Jederzeit abbestellbar.             <\/p>\n        \n        \n                    <div class=\"w-full max-w-[680px]\">\n                <form action=\"https:\/\/www.chromacon.com\/de\/wp-json\/ws-form\/v1\/submit\" class=\"wsf-form wsf-form-canvas\" id=\"ws-form-1\" data-id=\"4\" method=\"POST\" data-instance-id=\"1\" data-wsf-style-id=\"3\"><\/form>            <\/div>\n            <\/div>\n\n    <\/div><\/section><section id=\"block_3c2bf95a6c1c192f5fa20d4707a5de29\" class=\"block-trust py-fluid-4xl md:pt-fluid-5xl md:pb-fluid-4xl bg-gray-50 typo-off alignfull  \">\n    <!-- Smart wrapper section -->\n    <section class=\"wrapper-bl-l\">\n        <div class=\"flex flex-col md:flex-row items-stretch\">\n            <div class=\"md:w-1\/2 flex flex-col\">\n                <div class=\"mb-fluid-l md:mb-fluid-2xl max-w-[700px] md:mr-16\">\n                                                                    <h2 class=\"text-display-m leading-display-m leading-h1 md:text-h1 text-primary-800 mt-0 text-center md:text-left [&#038;_strong]:font-normal [&#038;_strong]:text-secondary-700\">Vertrauen von Branchenf\u00fchrern <strong>weltweit<\/strong><\/h2>\n                                                        <\/div>\n                                    <div class=\"bg-white py-fluid-xs md:py-fluid-l pl-0 md:px-fluid-xl divide-y divide-primary-950\/10 mr-responsive-negative\">\n                                                                                <div class=\"flex gap-4 p-fluid-xs md:pt-fluid-s-plus md:pb-fluid-s first:pt-0 last:pb-0 gap-fluid-2xs md:gap-fluid-m md:px-0 md:pr-2.5\">\n                                                                <div class=\"flex-1\">\n                                                                            <h3 class=\"heading-h4 !mt-0 !mb-2.5\">Bew\u00e4hrte Expertise<\/h3>\n                                                                                                                <p class=\"text-gray-600 text-16 md:text-18\">\n                                            Mit jahrzehntelanger Erfahrung liefert YMC ChromaCon Chromatographiesysteme, denen Wissenschaftler und Hersteller weltweit vertrauen.                                        <\/p>\n                                                                    <\/div>\n                            <\/div>\n                                                                                <div class=\"flex gap-4 p-fluid-xs md:pt-fluid-s-plus md:pb-fluid-s first:pt-0 last:pb-0 gap-fluid-2xs md:gap-fluid-m md:px-0 md:pr-2.5\">\n                                                                <div class=\"flex-1\">\n                                                                            <h3 class=\"heading-h4 !mt-0 !mb-2.5\">Zertifizierte Qualit\u00e4t<\/h3>\n                                                                                                                <p class=\"text-gray-600 text-16 md:text-18\">\n                                            Unsere Produkte und Prozesse entsprechen internationalen Standards, einschlie\u00dflich GMP- und ISO-Zertifizierungen, und gew\u00e4hrleisten Zuverl\u00e4ssigkeit sowie regulatorische Compliance.                                        <\/p>\n                                                                    <\/div>\n                            <\/div>\n                                                                                <div class=\"flex gap-4 p-fluid-xs md:pt-fluid-s-plus md:pb-fluid-s first:pt-0 last:pb-0 gap-fluid-2xs md:gap-fluid-m md:px-0 md:pr-2.5\">\n                                                                <div class=\"flex-1\">\n                                                                            <h3 class=\"heading-h4 !mt-0 !mb-2.5\">Innovative Technologien<\/h3>\n                                                                                                                <p class=\"text-gray-600 text-16 md:text-18\">\n                                            Propriet\u00e4re Technologien der kontinuierlichen Chromatographie, die die Grenzen von Aufreinigungseffizienz und Nachhaltigkeit verschieben.                                        <\/p>\n                                                                    <\/div>\n                            <\/div>\n                                                                                <div class=\"flex gap-4 p-fluid-xs md:pt-fluid-s-plus md:pb-fluid-s first:pt-0 last:pb-0 gap-fluid-2xs md:gap-fluid-m md:px-0 md:pr-2.5\">\n                                                                <div class=\"flex-1\">\n                                                                            <h3 class=\"heading-h4 !mt-0 !mb-2.5\">Globale Wirkung<\/h3>\n                                                                                                                <p class=\"text-gray-600 text-16 md:text-18\">\n                                            Eingesetzt von f\u00fchrenden biopharmazeutischen Unternehmen, um die Arzneimittelentwicklung und -produktion zu beschleunigen.                                        <\/p>\n                                                                    <\/div>\n                            <\/div>\n                                                                                <div class=\"flex gap-4 p-fluid-xs md:pt-fluid-s-plus md:pb-fluid-s first:pt-0 last:pb-0 gap-fluid-2xs md:gap-fluid-m md:px-0 md:pr-2.5\">\n                                                                <div class=\"flex-1\">\n                                                                            <h3 class=\"heading-h4 !mt-0 !mb-2.5\">Kundenerfolg<\/h3>\n                                                                                                                <p class=\"text-gray-600 text-16 md:text-18\">\n                                            Zahlreiche validierte Fallstudien zeigen konsistente Verbesserungen bei Ausbeute, Reinheit und Kosteneffizienz.                                        <\/p>\n                                                                    <\/div>\n                            <\/div>\n                                            <\/div>\n                            <\/div>\n            <div class=\"w-full md:w-1\/2 overflow-hidden md:pt-fluid-s flex flex-col gap-y-fluid-xl items-center justify-center md:h-full md:max-h-[70%]\">\n                                                            <img decoding=\"async\" src=\"https:\/\/www.chromacon.com\/wp-content\/uploads\/2026\/01\/Gemini_Generated_Image_nrdypinrdypinrdy.png\"\n                            alt=\"\"\n                            width=\"1168\"\n                            height=\"912\"\n                            class=\"w-full h-full object-cover aspect-video md:aspect-auto !m-0\">\n                                                <\/div>\n        <\/div>\n    <\/section>\n<\/section><section id=\"block_cfd0b7240ecde0b228a7400cbed17aec\" class=\"block-call-to-action py-fluid-6xl bg-secondary-700 alignfull  \" style=\"--block-bg-image: url(https:\/\/www.chromacon.com\/wp-content\/themes\/chromacon\/assets\/img\/layout\/block-background-poly.svg);\"><div class=\"l-wrap\">\n    <div class=\"flex flex-col gap-6 items-center text-center\">\n                    <p class=\"heading-display-m mx-auto !text-white !my-0 max-w-[1015px]\">\n                F\u00f6rdern Sie<br \/>\r\nIhre Karriere in der<br \/>\r\nChromatographie-Innovation            <\/p>\n        \n                    <div class=\"block-call-to-action__buttons mt-fluid-m flex flex-row flex-wrap justify-center items-center gap-[30px]\">\n                <span class=\"c-btn-focus-wrapper\"><a href=\"https:\/\/www.chromacon.com\/de\/karriere\/\" class=\"c-btn c-btn--regular c-btn--primary c-btn--light\" style=\"--bg-color: var(--color-primary-800); --border-color: var(--color-primary-800); --bg-hover-color: var(--color-primary-700); --border-hover-color: var(--color-primary-700);\"><span>Offene Stellen ansehen<\/span><\/a><\/span>                <span class=\"c-btn-focus-wrapper\"><a href=\"https:\/\/www.chromacon.com\/de\/technologieuebersicht\/\" class=\"c-btn c-btn--regular c-btn--secondary c-btn--dark\"><span>Entdecken Sie unsere Technologien<\/span><\/a><\/span>            <\/div>\n        \n            <\/div>\n\n    <\/div><\/section>","protected":false},"excerpt":{"rendered":"<p>Das YMC-\u00d6kosystem: Systeme, Medien und globaler Support<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_seopress_robots_primary_cat":"","_seopress_titles_title":"\u00dcber ChromaCon \u2014 Kontinuierliche Chromatographie | YMC ChromaCon","_seopress_titles_desc":"YMC ChromaCon entwickelt die Contichrom\u00ae-Plattform f\u00fcr kontinuierliche Chromatographie in Z\u00fcrich, Schweiz, und bedient Biopharma-Hersteller weltweit.","_seopress_robots_index":"","_seopress_analysis_target_kw":"","footnotes":""},"class_list":["post-7774","page","type-page","status-publish",""],"acf":[],"_links":{"self":[{"href":"https:\/\/www.chromacon.com\/de\/wp-json\/wp\/v2\/pages\/7774","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.chromacon.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.chromacon.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.chromacon.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.chromacon.com\/de\/wp-json\/wp\/v2\/comments?post=7774"}],"version-history":[{"count":9,"href":"https:\/\/www.chromacon.com\/de\/wp-json\/wp\/v2\/pages\/7774\/revisions"}],"predecessor-version":[{"id":8710,"href":"https:\/\/www.chromacon.com\/de\/wp-json\/wp\/v2\/pages\/7774\/revisions\/8710"}],"wp:attachment":[{"href":"https:\/\/www.chromacon.com\/de\/wp-json\/wp\/v2\/media?parent=7774"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}